{"id":176871,"date":"2022-11-22T08:30:43","date_gmt":"2022-11-22T13:30:43","guid":{"rendered":"https:\/\/howtoremove.guide\/?p=176871"},"modified":"2022-11-23T02:24:29","modified_gmt":"2022-11-23T07:24:29","slug":"tcbu-virus-fichier","status":"publish","type":"post","link":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/","title":{"rendered":"Tcbu Virus"},"content":{"rendered":"\n<h2 id=\"tcbu\" class=\"wp-block-heading\"><strong>Tcbu<\/strong><\/h2>\n\n\n\n<p>Tcbu est un virus ransomware qui demande \u00e0 ses victimes de payer une ran\u00e7on en \u00e9change de l&rsquo;acc\u00e8s \u00e0 leurs informations crypt\u00e9es. Tcbu utilise un code cryptographique complexe pour rendre inaccessibles les fichiers les plus utilis\u00e9s de la victime, puis la fait chanter pour qu&rsquo;elle paie une cl\u00e9 de d\u00e9cryptage.<\/p>\n\n\n\n<p>Vous \u00eates tr\u00e8s probablement int\u00e9ress\u00e9 par la lecture de notre article car Tcbu a secr\u00e8tement crypt\u00e9 vos fichiers les plus pr\u00e9cieux et vous a demand\u00e9 de transf\u00e9rer de l&rsquo;argent sur le compte de crypto-monnaie de certains criminels anonymes. L&rsquo;option propos\u00e9e par les pirates n&rsquo;est cependant pas la seule r\u00e9ponse \u00e0 votre probl\u00e8me. Il existe quelques m\u00e9thodes alternatives qui pourraient potentiellement vous aider \u00e0 \u00e9viter le paiement de la ran\u00e7on et \u00e0 r\u00e9cup\u00e9rer tout de m\u00eame certaines de vos donn\u00e9es. Dans les prochaines lignes, nous vous en dirons plus \u00e0 leur sujet et vous fournirons des instructions sur la fa\u00e7on de supprimer le redoutable ransomware Tcbu de votre syst\u00e8me.<\/p>\n\n\n\n<h2 id=\"le-virus-tcbu\" class=\"wp-block-heading\"><strong>Le virus Tcbu<\/strong><\/h2>\n\n\n\n<p>Le virus Tcbu est un programme bas\u00e9 sur un ransomware qui peut analyser un ordinateur et crypter les donn\u00e9es les plus couramment utilis\u00e9es qui y sont stock\u00e9es. Ensuite, le virus Tcbu demande g\u00e9n\u00e9ralement un paiement en bitcoins afin de fournir \u00e0 ses victimes une cl\u00e9 de d\u00e9cryptage des fichiers.<\/p>\n\n\n\n<p>Les ransomwares tels que Tcbu, Moia, Rigj sont g\u00e9n\u00e9ralement con\u00e7us pour rien de plus qu&rsquo;un simple chantage. Ils peuvent s&rsquo;infiltrer dans un ordinateur en secret et crypter une liste sp\u00e9cifique de fichiers sur votre ordinateur sans \u00eatre d\u00e9tect\u00e9s. Une fois cette t\u00e2che termin\u00e9e, ils semblent faire quelque chose d&rsquo;encore plus inqui\u00e9tant. Ils affichent un message sur l&rsquo;appareil infect\u00e9 qui indique que vous \u00eates cens\u00e9 payer une ran\u00e7on si vous voulez que vos donn\u00e9es soient \u00e0 nouveau accessibles. Le montant demand\u00e9 peut varier consid\u00e9rablement d&rsquo;un cas \u00e0 l&rsquo;autre, mais dans certaines situations, les escrocs \u00e0 l&rsquo;origine du ransomware peuvent exiger l&rsquo;\u00e9quivalent de quelques milliers de dollars en bitcoins.<\/p>\n\n\n\n<p>Les modes de diffusion de Tcbu peuvent aller de la distribution d&rsquo;un logiciel aux courriels de spam et \u00e0 leurs pi\u00e8ces jointes. Il convient toutefois de pr\u00e9ciser que les ransomwares arrivent rarement seuls. Il s&rsquo;introduit normalement dans le syst\u00e8me \u00e0 l&rsquo;aide d&rsquo;un cheval de Troie qui exploite les failles de votre syst\u00e8me d&rsquo;exploitation ou les programmes suppl\u00e9mentaires install\u00e9s sur votre ordinateur. Par cons\u00e9quent, lorsque vous supprimez le Ransomware, vous devez \u00e9galement vous assurer que votre syst\u00e8me ne contient pas de cheval de Troie cach\u00e9 et le supprimer \u00e9galement.<\/p>\n\n\n\n<h2 id=\"le-cryptage-du-fichier-tcbu\" class=\"wp-block-heading\"><strong>Le cryptage du fichier .Tcbu<\/strong><\/h2>\n\n\n\n<p>Le cryptage de fichier .Tcbu est une m\u00e9thode utilis\u00e9e pour coder des fichiers et les rendre inaccessibles \u00e0 des fins d&rsquo;extorsion de fonds. Le cryptage du fichier .Tcbu peut fonctionner en arri\u00e8re-plan du syst\u00e8me et passer inaper\u00e7u pour la plupart des programmes de s\u00e9curit\u00e9.<\/p>\n\n\n\n<p>Les deux questions les plus pressantes qui nous sont fr\u00e9quemment pos\u00e9es sont de savoir si c&rsquo;est une bonne id\u00e9e de payer la ran\u00e7on demand\u00e9e et si les informations crypt\u00e9es peuvent \u00eatre r\u00e9cup\u00e9r\u00e9es. Malheureusement, il n&rsquo;existe pas de r\u00e9ponse universelle pour tous les cas d&rsquo;infection par ransomware. Toutefois, ce n&rsquo;est JAMAIS une bonne id\u00e9e d&rsquo;envoyer de l&rsquo;argent \u00e0 des criminels anonymes, quelles que soient leurs promesses. En effet, vous ne pouvez pas \u00eatre s\u00fbr qu&rsquo;une fois qu&rsquo;ils auront re\u00e7u l&rsquo;argent, ils vous aideront \u00e0 r\u00e9cup\u00e9rer vos fichiers. Par cons\u00e9quent, nous vous recommandons d&rsquo;essayer d&rsquo;autres m\u00e9thodes de lutte contre Tcbu avant de risquer votre argent. Si vous d\u00e9cidez de supprimer Tcbu et d&rsquo;essayer d&rsquo;extraire les donn\u00e9es des sauvegardes du syst\u00e8me, notre guide de suppression est l\u00e0 pour vous aider.<\/p>\n\n\n\n<p><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\"><strong>R\u00e9sum\u00e9:<\/strong><\/span><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><span style=\"font-family: helvetica, arial, sans-serif;\">Nom<\/span><\/td><td><span style=\"text-decoration: underline; font-family: helvetica, arial, sans-serif;\"><strong><strong><strong><strong>Tcbu<\/strong><\/strong><\/strong><\/strong><\/span><\/td><\/tr><tr><td><span style=\"font-family: helvetica, arial, sans-serif;\">Type<\/span><\/td><td><span style=\"font-family: helvetica, arial, sans-serif;\"><em>Ransomware<\/em><\/span><\/td><\/tr><tr><td><span style=\"font-family: helvetica, arial, sans-serif;\">Outil de d\u00e9tection<\/span><\/td><td><div class='code-block code-block-13' style='margin: 8px 0; clear: both;'>\n<div><a class=\"banner\" href=\"https:\/\/howtoremove.guide\/download-pc-spyhunter-fr\/\" id=\"table_v2_fr\" style=\"display: block;text-underline: none; background: transparent; color: rgb(18, 133, 182);text-decoration:none\" target=\"_blank\"><span style=\"color:black\">Certaines menaces se r&eacute;installent d&#39;elles-m&ecirc;mes si vous ne supprimez pas leurs fichiers de base. Nous vous recommandons de t&eacute;l&eacute;charger SpyHunter pour supprimer les programmes nuisibles pour vous. <strong>Cela peut vous faire gagner des heures et vous &eacute;viter de nuire &agrave; votre syst&egrave;me en supprimant les mauvais fichiers.<\/strong><\/span><br \/>\n<strong style=\"font-weight:normal\"><strong><span style=\"font-size:14px\"><span style=\"background-color:#008fec; border-radius:5px; color:white; display:block; font-size:16px; margin:12px auto 12px auto; max-width:385px; padding:12px; text-align:center\">T&eacute;l&eacute;charger SpyHunter (Suppression Gratuite*)<\/span><\/span><\/strong><\/strong><\/a><strong style=\"font-weight:normal\"> <\/strong>\n<div class=\"col-lg-12\" style=\"padding:10px 30px 6px\"><span style=\"color:grey; font-size:11px; margin-bottom:4px; padding-right:30px; padding-top:10px\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" alt=\"\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2020\/06\/Offer-icon-1.svg\" style=\"height:12px; margin-right:4px; width:12px\" \/>OFFRE<\/span>&nbsp;<span style=\"font-size:11px\">*Suppression gratuite\/ vous permet, sous r&eacute;serve d&#39;une p&eacute;riode d&#39;attente de 48 heures, de proc&eacute;der &agrave; une correction et &agrave; une suppression pour les r&eacute;sultats trouv&eacute;s.&nbsp;Le CLUF de SpyHunter, la politique de confidentialit&eacute;<\/span><span style=\"color:#9a9a9a; font-size:11px; text-align:center\">&nbsp;et&nbsp;<\/span><a href=\"https:\/\/howtoremove.guide\/more-details-about-spyhunter-free-remover\/\" style=\"font-size: 11px; text-align: center;\">plus de d&eacute;tails sur Suppression Gratuite<\/a><span style=\"color:#9a9a9a; font-size:11px; text-align:center\">.<\/span><\/div>\n<strong style=\"font-weight:normal\"> <\/strong><\/div><\/div>\n<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 id=\"supprimer-tcbu-ransomware\" class=\"wp-block-heading\" id=\"block-ac1f9d5d-1636-4d0a-bb57-6f0e19dad8bf\"><strong>Supprimer Tcbu Ransomware<\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator\" id=\"block-c05b901b-d5c0-4ad0-9b7d-019c6187d9b6\"\/>\n\n\n\n<figure class=\"wp-block-image\" id=\"block-468052e1-15e2-424e-87b8-394d5bb053d2\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png\" alt=\"Step1\"\/><\/figure>\n\n\n\n<p id=\"block-1d5ead7a-560b-4730-b088-396a7d920952\">Dans la premi\u00e8re \u00e9tape de ce guide, nous vous recommandons d&rsquo;ajouter cette page aux favoris de votre navigateur, afin de l&rsquo;enregistrer et d&rsquo;y avoir acc\u00e8s jusqu&rsquo;\u00e0 ce que vous ayez termin\u00e9 le processus de suppression de Tcbu.<\/p>\n\n\n\n<p id=\"block-d02f4aa5-1ee3-4eb8-9462-ad9a1efb604e\">Ensuite, vous devez red\u00e9marrer l&rsquo;ordinateur infect\u00e9 par le ransomware Tcbu en mode sans \u00e9chec (<a href=\"https:\/\/howtoremove.guide\/how-to-enter-in-windows-safe-mode-all-versions\/\" target=\"_blank\" rel=\"noreferrer noopener\">suivez ce lien pour obtenir des instructions<\/a>) afin que seuls les programmes et processus les plus basiques soient ex\u00e9cut\u00e9s sur votre syst\u00e8me. De cette fa\u00e7on, vous serez en mesure d&rsquo;identifier et de mettre fin aux processus li\u00e9s \u00e0 Tcbu plus facilement.<\/p>\n\n\n\n<p id=\"block-b19e9240-dd89-46a2-b614-f252cebfa5c7\">Apr\u00e8s avoir red\u00e9marr\u00e9 en mode sans \u00e9chec, cliquez sur le menu D\u00e9marrer, entrez \u00ab\u00a0msconfig\u00a0\u00bb dans la zone de recherche et appuyez sur Entr\u00e9e. Une fois que vous avez fait cela, la configuration du syst\u00e8me s&rsquo;ouvre \u00e0 l&rsquo;\u00e9cran. V\u00e9rifiez la liste des \u00e9l\u00e9ments de d\u00e9marrage pour voir si l&rsquo;un d&rsquo;entre eux est li\u00e9 au logiciel malveillant en cliquant sur l&rsquo;onglet D\u00e9marrage.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"block-a0c7a93d-f008-4a4a-b7ed-5bb22f6394a7\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/07\/msconfig_opt.png\" alt=\"msconfig_opt\"\/><\/figure>\n\n\n\n<p id=\"block-3c7183ea-3a4e-4526-9abe-ac988435a8ca\">Les entr\u00e9es dont le fabricant est \u00ab\u00a0Inconnu\u00a0\u00bb, les noms \u00e9tranges et les entr\u00e9es que vous ne pouvez connecter \u00e0 aucune application r\u00e9put\u00e9e sur votre PC doivent faire l&rsquo;objet de recherches en ligne. Si les informations que vous d\u00e9couvrez \u00e0 leur sujet indiquent qu&rsquo;elles pr\u00e9sentent un risque, la meilleure chose \u00e0 faire est de d\u00e9cocher la case correspondante.<\/p>\n\n\n\n<p id=\"block-fc3fa66d-56e9-434e-ad8d-eb6a0bb332a7\">Une fois que vous avez termin\u00e9, cliquez \u00e0 nouveau sur le bouton du menu D\u00e9marrer en bas \u00e0 gauche, tapez soigneusement chacun des emplacements \u00e9crits ci-dessous dans la barre de recherche, un par un, et appuyez sur Entr\u00e9e pour les ouvrir :<\/p>\n\n\n\n<ol class=\"wp-block-list\" id=\"block-85d54bad-653b-4e80-9606-3daa27804399\"><li><strong>%AppData%<\/strong><\/li><li><strong>%LocalAppData%<\/strong><\/li><li><strong>%ProgramData%<\/strong><\/li><li><strong>%WinDir%<\/strong><\/li><li><strong>%Temp%<\/strong><\/li><\/ol>\n\n\n\n<p id=\"block-ee531ae2-0732-4fca-a0d5-3e8ad2da3522\">Recherchez les fichiers et les dossiers portant des noms \u00e9tranges qui ont \u00e9t\u00e9 ajout\u00e9s \u00e0 peu pr\u00e8s au moment de l&rsquo;infection par le ransomware dans chaque emplacement. Si vous pensez que quelque chose doit \u00eatre \u00e9limin\u00e9, faites-le avec prudence.<\/p>\n\n\n\n<p id=\"block-cea01d1c-8410-43a8-9e5e-9cf63b919657\">Lorsque vous entrez dans Temp, s\u00e9lectionnez tout ce qui se trouve dans ce dossier, puis supprimez-le. Cela permettra d&rsquo;effacer du syst\u00e8me tous les fichiers temporaires cr\u00e9\u00e9s par le ransomware.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"block-6b01a79d-6850-426d-bfd5-7716dbd88725\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step2.png\" alt=\"Step2\"\/><\/figure>\n\n\n\n<p id=\"block-fd13a6be-01eb-4466-a5c1-1657561ee643\"><strong><strong>ATTENTION! LIRE ATTENTIVEMENT AVANT DE PROCEDER!<\/strong><\/strong><\/p>\n\n\n\n<p id=\"block-73b89133-cb99-42ff-9ede-c0f748303f0a\"><div class='code-block code-block-26' style='margin: 8px 0; clear: both;'>\n<div class=\"col_8 row\" id=\"firstguide_fr\">\n<div class=\"box-warning col-lg-12\" style=\"background:url(\/wp-content\/uploads\/2020\/02\/web-10.jpg)95px 6px no-repeat; margin-bottom:60px; margin-left:60px; margin-right:60px; margin-top:60px; padding-left:180px\">\n<p style=\"font-size:16px; text-align:left\">On nous pose souvent cette question, nous y r&eacute;pondons donc ici: La suppression manuelle du parasite peut prendre des heures et endommager votre syst&egrave;me au cours du processus. Nous vous recommandons de&nbsp;<a href=\"https:\/\/howtoremove.guide\/download-pc-spyhunter-fr\/\" style=\"color: #4138FF;\">t&eacute;l&eacute;charger SpyHunter<\/a>&nbsp;<span style=\"color:#2f5496\">pour voir s&#39;il peut d&eacute;tecter&nbsp;parasite&nbsp;sur votre machine.<\/span><\/p>\n<p style=\"color:#9a9a9a; font-size:10px; text-align:center\"><strong><a href=\"https:\/\/howtoremove.guide\/more-details-about-spyhunter-free-remover\/\" target=\"_blank\">Plus d&#39;informations sur&nbsp;SpyHunter<\/a>,&nbsp;les &eacute;tapes de d&eacute;sinstallation,&nbsp;le CLUF <\/strong><strong>&nbsp;et la politique de confidentialit&eacute;.<\/strong><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n\n<p id=\"block-9bf5037f-fa98-4049-a55e-0dc02c50e87f\">\u00c0 l&rsquo;\u00e9tape suivante, v\u00e9rifiez si des processus malveillants sont actifs dans le syst\u00e8me. Cliquez sur l&rsquo;onglet Processus dans la fen\u00eatre du Gestionnaire des t\u00e2ches qui appara\u00eet en appuyant sur les touches CTRL + SHIFT + ESC du clavier.<\/p>\n\n\n\n<p id=\"block-68f52d68-51ad-4931-a8f3-59aa28abcd6f\">Utilisez les colonnes CPU et Utilisation de la m\u00e9moire pour voir si des processus suspects s&rsquo;ex\u00e9cutent en arri\u00e8re-plan de votre syst\u00e8me. Essayez ensuite de les isoler en examinant leur nom, leur intitul\u00e9 ou la quantit\u00e9 de ressources qu&rsquo;ils consomment pendant leur ex\u00e9cution.<\/p>\n\n\n\n<p id=\"block-60ea382b-4f1e-4011-a734-f2bfbddc5141\">Cliquez avec le bouton droit de la souris sur tout processus qui semble \u00eatre nuisible et s\u00e9lectionnez Ouvrir l&#8217;emplacement du fichier dans le menu contextuel.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"block-baa31645-35fe-4979-9a89-a3f30f6c2a62\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/05\/malware-start-taskbar.jpg\" alt=\"malware-start-taskbar\"\/><\/figure>\n\n\n\n<p id=\"block-c7ae7d87-620a-4f49-a3f9-9f119f203202\"><strong>Ensuite, vous pouvez utiliser l&rsquo;antivirus en ligne gratuit ci-dessous pour rechercher les logiciels malveillants dans les fichiers du dossier Emplacement du fichier.<\/strong><\/p>\n\n\n\n<p id=\"block-f3b74b1b-cb80-4a5d-89b5-ee663107e5ba\"><div class=\"vtas\"><div class=\"vtas__head\"><div class=\"vtas__head-title vtas__head-title_1 vtas__head-title_active\">Each file will be scanned with up to 64 antivirus programs to ensure maximum accuracy<\/div><div class=\"vtas__head-title vtas__head-title_2\">This scanner is free and will always remain free for our website's users.<\/div><\/div><div class=\"vtas__body\"><div class=\"vtas__not-matched\"><div class=\"vtas__not-matched-title\">This file is not matched with any known malware in the database. You can either do a full real-time scan of the file or skip it to upload a new file. Doing a full scan with 64 antivirus programs can take up to 3-4 minutes per file.<\/div><div class=\"vtas__not-matched-buttons\"><a href=\"javascript: void(0);\" class=\"vtas__not-matched-full-scan\">Full Scan<\/a><a href=\"javascript: void(0);\" class=\"vtas__not-matched-upload-new-file\">Upload New File<\/a><\/div><\/div><div class=\"vtas__dropzone clearfix\"><div class=\"vtas__dropzone-drag\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/plugins\/virustotal-api-shortcode\/\/static\/images\/files-icon 1.svg\" alt=\"Drag and Drop File Here To Scan\"><div class=\"vtas__dropzone-title\">Drag and Drop File Here To Scan<\/div><\/div><div class=\"vtas__dropzone-button-section\"><button class=\"vtas__dropzone-button\">Upload File<\/div><input type=\"file\" id=\"vtas-selectfile\" class=\"vtas__dropzone-input\"><\/div><div class=\"vtas__loading\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/plugins\/virustotal-api-shortcode\/\/static\/images\/ajax-loader 1.png\" alt=\"Loading\" class=\"vtas__loading-icon\"><div class=\"vtas__loading-title\">Analyzing <span class=\"vtas__loading-time\">0<\/span> s<\/div><\/div><\/div><div class=\"vtas__bottom\">Each file will be scanned with up to 64 antivirus programs to ensure maximum accuracy<\/div><ul class=\"vtas__results\"><\/ul><div class=\"vtas__privacy\">This scanner is based on VirusTotal's API. By submitting data to it, you agree to their <a href=\"https:\/\/support.virustotal.com\/hc\/en-us\/articles\/115002145529-Terms-of-Service\">Terms of Service<\/a> and <a href=\"https:\/\/support.virustotal.com\/hc\/en-us\/articles\/115002168385-Privacy-Policy\">Privacy Policy<\/a>, and to the sharing of your sample submission with the security community. Please do not submit files with personal information if you do not want them to be shared.<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator\" id=\"block-6de5de36-70be-43c3-a7d5-92ead82122da\"\/>\n\n\n\n<p id=\"block-afceb20d-9653-4617-8a23-894fbead96cd\">Terminez le processus dont les fichiers ont \u00e9t\u00e9 identifi\u00e9s comme nuisibles par l&rsquo;analyseur, puis supprimez ces fichiers malveillants et leurs r\u00e9pertoires de l&rsquo;ordinateur.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step3.png\" alt=\"Step3\" class=\"wp-image-6476\" title=\"Step3\"\/><\/figure>\n\n\n\n<p>En utilisant la touche Windows et la touche R du clavier, lancez une fen\u00eatre de commande Ex\u00e9cuter. Copiez ensuite la ligne suivante dans celle-ci :<\/p>\n\n\n\n<p><strong>notepad %windir%\/system32\/Drivers\/etc\/hosts<\/strong><\/p>\n\n\n\n<p>Cliquez sur OK apr\u00e8s avoir copi\u00e9 la ligne, trouvez Localhost dans le texte du fichier Hosts qui appara\u00eet \u00e0 l&rsquo;\u00e9cran et cherchez des preuves de piratage. Si votre ordinateur a \u00e9t\u00e9 pirat\u00e9, vous verrez un tas d&rsquo;adresses IP au bas de votre fichier sous Localhost qui ont un aspect \u00e9trange, comme dans l&rsquo;image ci-dessous.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/07\/hosts_opt-1.png\" alt=\"hosts_opt (1)\" class=\"wp-image-3349\" title=\"Hosts file\"\/><\/figure>\n\n\n\n<p>Si vous trouvez quelque chose de douteux dans votre fichier Hosts, veuillez nous laisser y jeter un coup d&rsquo;\u0153il en nous laissant un commentaire en dessous de cet article, et nous vous donnerons des conseils sur ce qu&rsquo;il faut faire si nous trouvons quelque chose de suspect.<\/p>\n\n\n\n<p>Si votre fichier Hosts semble \u00eatre propre, vous pouvez le fermer et passer \u00e0 l&rsquo;\u00e9tape suivante sans plus attendre.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step4.png\" alt=\"Step4\" class=\"wp-image-6477\" title=\"Step4\"\/><\/figure>\n\n\n\n<div class='code-block code-block-27' style='margin: 8px 0; clear: both;'>\n<div class=\"grey-bg\" id=\"secondguide_fr\" style=\"background:#fcfcfc url(\/wp-content\/uploads\/2020\/01\/web-11.png) 25px 65px no-repeat; box-shadow:4px 10px 8px -6px rgba(239, 239, 239, 0.9); margin-bottom:25px; padding:20px 20px 20px 130px; position:relative; text-align:left\">\n<p style=\"font-size:16px; margin-bottom:30px; margin-top:0px\">Pour que vous supprimiez le <strong>parasite<\/strong> vous-m&ecirc;me, vous devrez peut-&ecirc;tre vous occuper des fichiers syst&egrave;me et des registres. <span style=\"font-size:12.0pt\"><span style=\"line-height:107%\"><span> <\/span><\/span><\/span><span style=\"color:#2f5496\">Si vous devez faire cela, soyez extr&ecirc;mement prudent, car vous pourriez endommager votre syst&egrave;me.<\/span><\/p>\n<p style=\"font-size:16px; margin-bottom:30px; margin-top:0px\"><span style=\"color:#2f5496\">Si vous voulez &eacute;viter le risque, nous vous recommandons de <a href=\"https:\/\/howtoremove.guide\/download-pc-spyhunter-fr\/\">t&eacute;l&eacute;charger SpyHunter<\/a>, un outil professionnel de suppression de logiciels malveillants.<\/span><\/p>\n<p style=\"color:#9a9a9a; font-size:10px; text-align:center\"><strong><a href=\"https:\/\/howtoremove.guide\/more-details-about-spyhunter-free-remover\/\" target=\"_blank\">Plus d&#39;informations sur&nbsp;SpyHunter<\/a>,&nbsp;les &eacute;tapes de d&eacute;sinstallation,&nbsp;le CLUF <\/strong><strong>&nbsp;et la politique de confidentialit&eacute;.<\/strong><\/p>\n<\/div><\/div>\n\n\n\n\n<p>Les entr\u00e9es malveillantes du registre qui ont \u00e9t\u00e9 ajout\u00e9es \u00e0 l&rsquo;insu de la victime sont souvent la raison pour laquelle les menaces de ransomware comme Tcbu ont tendance \u00e0 r\u00e9appara\u00eetre sur le syst\u00e8me et sont difficiles \u00e0 supprimer. Par cons\u00e9quent, si vous voulez traiter l&rsquo;infection efficacement, le registre de votre ordinateur doit \u00eatre soigneusement v\u00e9rifi\u00e9 \u00e0 la recherche de tels fichiers.<\/p>\n\n\n\n<p>Pour cela, lancez l&rsquo;\u00c9diteur du Registre (tapez Regedit dans la barre de recherche de Windows et cliquez sur Entr\u00e9e sur le clavier) et utilisez CTRL et F pour rechercher les entr\u00e9es li\u00e9es \u00e0 l&rsquo;infection. Tapez simplement le nom du ransomware dans la zone de recherche qui s&rsquo;affiche, puis cliquez sur Suivant.<\/p>\n\n\n\n<p><strong><em>\u00c9vitez de supprimer les fichiers et r\u00e9pertoires qui ne sont pas li\u00e9s \u00e0 Tcbu tout en supprimant ceux qui apparaissent dans les r\u00e9sultats, car cela pourrait endommager votre syst\u00e8me d&rsquo;exploitation. Il est pr\u00e9f\u00e9rable d&rsquo;utiliser un programme de suppression professionnel, tel que celui sugg\u00e9r\u00e9 sur cette page, pour \u00e9viter tout dommage involontaire au syst\u00e8me. La d\u00e9tection et la suppression des logiciels malveillants des emplacements sensibles du syst\u00e8me, tels que le registre, sont les points forts de ce programme.<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step5.png\" alt=\"Step5\" class=\"wp-image-6478\" title=\"Step 5\"\/><\/figure>\n\n\n\n<p><strong>Comment d\u00e9crypter les fichiers Tcbu<\/strong><\/p>\n\n\n\n<p>Selon le type de virus, le d\u00e9cryptage des donn\u00e9es crypt\u00e9es peut n\u00e9cessiter une approche totalement diff\u00e9rente. Les extensions des fichiers crypt\u00e9s peuvent r\u00e9v\u00e9ler la variante pr\u00e9cise du ransomware qui vous a attaqu\u00e9.<\/p>\n\n\n\n<p>Mais d&rsquo;abord, veuillez utiliser l&rsquo;aide d&rsquo;un logiciel antivirus professionnel, tel que ceux mentionn\u00e9s sur ce site, pour vous d\u00e9barrasser de Tcbu et des autres infections. Une fois le ransomware supprim\u00e9 de votre ordinateur, vous pouvez commencer le processus de d\u00e9cryptage des donn\u00e9es qui ont pu \u00eatre chiffr\u00e9es.<\/p>\n\n\n\n<p><strong>Nouveau Djvu Ransomware<\/strong><\/p>\n\n\n\n<p>STOP Djvu, la variante la plus r\u00e9cente de l&rsquo;infection par le ransomware Djvu, chiffre les donn\u00e9es en attachant le suffixe .Tcbu aux fichiers encod\u00e9s. Au moment o\u00f9 cet article est \u00e9crit, seuls les fichiers crypt\u00e9s avec une cl\u00e9 hors ligne peuvent actuellement \u00eatre d\u00e9chiffr\u00e9s. Consultez ce lien pour obtenir un programme de d\u00e9cryptage qui pourrait vous aider \u00e0 r\u00e9cup\u00e9rer vos donn\u00e9es :<\/p>\n\n\n\n<p><a href=\"https:\/\/www.emsisoft.com\/ransomware-decryption-tools\/stop-djvu\">https:\/\/www.emsisoft.com\/ransomware-decryption-tools\/stop-djvu<\/a><\/p>\n\n\n\n<p><strong>D\u00e9cryptage<\/strong><\/p>\n\n\n\n<p>Pour obtenir le d\u00e9crypteur STOPDjvu.exe, il vous suffit de suivre le lien fourni ci-dessus et de choisir \u00ab\u00a0T\u00e9l\u00e9charger\u00a0\u00bb.<\/p>\n\n\n\n<p>Une fois le fichier t\u00e9l\u00e9charg\u00e9 sur l&rsquo;ordinateur, s\u00e9lectionnez \u00ab\u00a0Ex\u00e9cuter en tant qu&rsquo;administrateur\u00a0\u00bb, puis appuyez sur le bouton Oui pour lancer l&rsquo;application. Cliquez sur le bouton D\u00e9crypter pour commencer \u00e0 d\u00e9crypter vos donn\u00e9es apr\u00e8s avoir lu le contrat de licence et les br\u00e8ves instructions. Veuillez noter que les fichiers qui ont \u00e9t\u00e9 chiffr\u00e9s avec des cl\u00e9s hors ligne inconnues ou un chiffrement en ligne ne peuvent pas \u00eatre d\u00e9chiffr\u00e9s \u00e0 l&rsquo;aide de cet outil.<\/p>\n\n\n\n<p>Pour plus d&rsquo;aide, veuillez utiliser le logiciel anti-virus list\u00e9 sur cette page ou le <a href=\"https:\/\/howtoremove.guide\/online-virus-scanner\/\" target=\"_blank\" rel=\"noreferrer noopener\">scanner de virus en ligne gratuit<\/a> pour garantir que Tcbu a \u00e9t\u00e9 compl\u00e8tement supprim\u00e9 du syst\u00e8me. Si vous avez des questions, n&rsquo;h\u00e9sitez pas \u00e0 les poser dans la section des commentaires ci-dessous.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tcbu Tcbu est un virus ransomware qui demande \u00e0 ses victimes de payer une ran\u00e7on en \u00e9change de l&rsquo;acc\u00e8s \u00e0 leurs informations crypt\u00e9es. Tcbu utilise un code cryptographique complexe pour rendre inaccessibles les fichiers les plus utilis\u00e9s de la victime, puis la fait chanter pour qu&rsquo;elle paie une cl\u00e9 de d\u00e9cryptage. Vous \u00eates tr\u00e8s probablement [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[244],"tags":[],"class_list":["post-176871","post","type-post","status-publish","format-standard","hentry","category-ransomware-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Supprimer Tcbu Virus Ransomware (.tcbu) Restaurer les fichiers<\/title>\n<meta name=\"description\" content=\"Tcbu est un virus ransomware qui demande \u00e0 ses victimes de payer une ran\u00e7on en \u00e9change de l&#039;acc\u00e8s \u00e0 leurs informations crypt\u00e9es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Supprimer Tcbu Virus Ransomware (.tcbu) Restaurer les fichiers\" \/>\n<meta property=\"og:description\" content=\"Tcbu est un virus ransomware qui demande \u00e0 ses victimes de payer une ran\u00e7on en \u00e9change de l&#039;acc\u00e8s \u00e0 leurs informations crypt\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/\" \/>\n<meta property=\"og:site_name\" content=\"HowToRemove.Guide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/howtoremove.guide\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-22T13:30:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-23T07:24:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png\" \/>\n<meta name=\"author\" content=\"George Slaine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GuideBasics\" \/>\n<meta name=\"twitter:site\" content=\"@GuideBasics\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Slaine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Supprimer Tcbu Virus Ransomware (.tcbu) Restaurer les fichiers","description":"Tcbu est un virus ransomware qui demande \u00e0 ses victimes de payer une ran\u00e7on en \u00e9change de l'acc\u00e8s \u00e0 leurs informations crypt\u00e9es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/","og_locale":"fr_FR","og_type":"article","og_title":"Supprimer Tcbu Virus Ransomware (.tcbu) Restaurer les fichiers","og_description":"Tcbu est un virus ransomware qui demande \u00e0 ses victimes de payer une ran\u00e7on en \u00e9change de l'acc\u00e8s \u00e0 leurs informations crypt\u00e9es.","og_url":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/","og_site_name":"HowToRemove.Guide","article_publisher":"https:\/\/www.facebook.com\/howtoremove.guide","article_published_time":"2022-11-22T13:30:43+00:00","article_modified_time":"2022-11-23T07:24:29+00:00","og_image":[{"url":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","type":"","width":"","height":""}],"author":"George Slaine","twitter_card":"summary_large_image","twitter_creator":"@GuideBasics","twitter_site":"@GuideBasics","twitter_misc":{"\u00c9crit par":"George Slaine","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/#article","isPartOf":{"@id":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/"},"author":{"name":"George Slaine","@id":"https:\/\/howtoremove.guide\/fr\/#\/schema\/person\/21c82db8a1f4d7cf888c5c02c079d8d8"},"headline":"Tcbu Virus","datePublished":"2022-11-22T13:30:43+00:00","dateModified":"2022-11-23T07:24:29+00:00","mainEntityOfPage":{"@id":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/"},"wordCount":1952,"commentCount":0,"publisher":{"@id":"https:\/\/howtoremove.guide\/fr\/#organization"},"image":{"@id":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/#primaryimage"},"thumbnailUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","articleSection":["Ransomware fr"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/","url":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/","name":"Supprimer Tcbu Virus Ransomware (.tcbu) Restaurer les fichiers","isPartOf":{"@id":"https:\/\/howtoremove.guide\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/#primaryimage"},"image":{"@id":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/#primaryimage"},"thumbnailUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","datePublished":"2022-11-22T13:30:43+00:00","dateModified":"2022-11-23T07:24:29+00:00","description":"Tcbu est un virus ransomware qui demande \u00e0 ses victimes de payer une ran\u00e7on en \u00e9change de l'acc\u00e8s \u00e0 leurs informations crypt\u00e9es.","breadcrumb":{"@id":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/#primaryimage","url":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","contentUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/howtoremove.guide\/fr\/tcbu-virus-fichier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/howtoremove.guide\/fr\/"},{"@type":"ListItem","position":2,"name":"Ransomware fr","item":"https:\/\/howtoremove.guide\/fr\/category\/ransomware-fr\/"},{"@type":"ListItem","position":3,"name":"Tcbu Virus"}]},{"@type":"WebSite","@id":"https:\/\/howtoremove.guide\/fr\/#website","url":"https:\/\/howtoremove.guide\/fr\/","name":"HowToRemove.Guide","description":"Virus &amp; Malware Removal","publisher":{"@id":"https:\/\/howtoremove.guide\/fr\/#organization"},"alternateName":"HowToRemove.guide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/howtoremove.guide\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/howtoremove.guide\/fr\/#organization","name":"HowToRemove.Guide","url":"https:\/\/howtoremove.guide\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/howtoremove.guide\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2018\/09\/howtoremove-logo-250-px.png","contentUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2018\/09\/howtoremove-logo-250-px.png","width":250,"height":42,"caption":"HowToRemove.Guide"},"image":{"@id":"https:\/\/howtoremove.guide\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/howtoremove.guide","https:\/\/x.com\/GuideBasics","https:\/\/www.youtube.com\/channel\/UCb61rHhYyMKutbMLc5r6w-w"]},{"@type":"Person","@id":"https:\/\/howtoremove.guide\/fr\/#\/schema\/person\/21c82db8a1f4d7cf888c5c02c079d8d8","name":"George Slaine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/howtoremove.guide\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/17047dcdf6307b0bc9558fc516840e6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17047dcdf6307b0bc9558fc516840e6c?s=96&d=mm&r=g","caption":"George Slaine"},"url":"https:\/\/howtoremove.guide\/fr\/author\/georges\/"}]}},"spectra_custom_meta":{"_edit_lock":["1669312140:22"],"VirusName":["Tcbu"],"_edit_last":["22"],"_single_add_custom_css":[""],"_vce_meta":["a:4:{s:11:\"use_sidebar\";s:7:\"inherit\";s:7:\"sidebar\";s:7:\"inherit\";s:14:\"sticky_sidebar\";s:7:\"inherit\";s:6:\"layout\";s:7:\"inherit\";}"],"_yoast_wpseo_primary_category":["244"],"_yoast_wpseo_title":["Supprimer Tcbu Virus Ransomware (.tcbu) Restaurer les fichiers %%page%%"],"_yoast_wpseo_metadesc":["Tcbu est un virus ransomware qui demande \u00e0 ses victimes de payer une ran\u00e7on en \u00e9change de l'acc\u00e8s \u00e0 leurs informations crypt\u00e9es."],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":["10"],"_yoast_wpseo_wordproof_timestamp":[""],"_uag_page_assets":["a:9:{s:3:\"css\";s:4944:\".wp-block-uagb-separator{text-align:center;box-sizing:border-box;line-height:0}.wp-block-uagb-separator__inner{display:inline-block}.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner{display:flex;justify-content:center;align-items:center;margin:0 auto}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::before,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::after,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::after{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--icon .wp-block-uagb-separator-element svg{font-size:30px;color:#333;fill:#333;width:30px;height:30px;line-height:30px;max-width:none}.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{word-break:initial;margin:0}\n.uagb-block-9f7858eb.wp-block-uagb-separator{text-align: center;}.uagb-block-9f7858eb.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-9f7858eb.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 90%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}@media only screen and (max-width: 976px) {.uagb-block-9f7858eb.wp-block-uagb-separator{text-align: center;}.uagb-block-9f7858eb.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-9f7858eb.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}@media only screen and (max-width: 767px) {.uagb-block-9f7858eb.wp-block-uagb-separator{text-align: center;}.uagb-block-9f7858eb.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-9f7858eb.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}.uagb-block-f3a675c7.wp-block-uagb-separator{text-align: center;}.uagb-block-f3a675c7.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-f3a675c7.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 90%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}@media only screen and (max-width: 976px) {.uagb-block-f3a675c7.wp-block-uagb-separator{text-align: center;}.uagb-block-f3a675c7.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-f3a675c7.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}@media only screen and (max-width: 767px) {.uagb-block-f3a675c7.wp-block-uagb-separator{text-align: center;}.uagb-block-f3a675c7.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-f3a675c7.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:33:{i:0;s:10:\"core\/group\";i:2;s:10:\"core\/image\";i:4;s:15:\"core\/navigation\";i:5;s:14:\"uagb\/separator\";i:7;s:15:\"core\/post-title\";i:9;s:16:\"core\/post-author\";i:10;s:14:\"core\/paragraph\";i:11;s:14:\"core\/post-date\";i:12;s:15:\"core\/post-terms\";i:15;s:24:\"core\/post-featured-image\";i:16;s:17:\"core\/post-content\";i:17;s:14:\"core\/separator\";i:19;s:13:\"core\/comments\";i:20;s:19:\"core\/comments-title\";i:21;s:21:\"core\/comment-template\";i:24;s:11:\"core\/avatar\";i:26;s:24:\"core\/comment-author-name\";i:28;s:17:\"core\/comment-date\";i:29;s:22:\"core\/comment-edit-link\";i:30;s:20:\"core\/comment-content\";i:31;s:23:\"core\/comment-reply-link\";i:32;s:24:\"core\/comments-pagination\";i:33;s:33:\"core\/comments-pagination-previous\";i:34;s:32:\"core\/comments-pagination-numbers\";i:35;s:29:\"core\/comments-pagination-next\";i:36;s:23:\"core\/post-comments-form\";i:38;s:12:\"core\/columns\";i:39;s:11:\"core\/column\";i:40;s:22:\"wpml\/language-switcher\";i:41;s:15:\"core\/site-title\";i:42;s:12:\"core\/heading\";i:43;s:10:\"core\/table\";i:44;s:9:\"core\/list\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1784059105;s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"rank_math_primary_category":["244"],"rank_math_title":["Supprimer Tcbu Virus Ransomware (.tcbu) Restaurer les fichiers %page%"],"rank_math_description":["Tcbu est un virus ransomware qui demande \u00e0 ses victimes de payer une ran\u00e7on en \u00e9change de l'acc\u00e8s \u00e0 leurs informations crypt\u00e9es."],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"_uag_css_file_name":["uag-css-176871.css"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"George Slaine","author_link":"https:\/\/howtoremove.guide\/fr\/author\/georges\/"},"uagb_comment_info":0,"uagb_excerpt":"Tcbu Tcbu est un virus ransomware qui demande \u00e0 ses victimes de payer une ran\u00e7on en \u00e9change de l&rsquo;acc\u00e8s \u00e0 leurs informations crypt\u00e9es. Tcbu utilise un code cryptographique complexe pour rendre inaccessibles les fichiers les plus utilis\u00e9s de la victime, puis la fait chanter pour qu&rsquo;elle paie une cl\u00e9 de d\u00e9cryptage. Vous \u00eates tr\u00e8s probablement\u2026","_links":{"self":[{"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/posts\/176871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/comments?post=176871"}],"version-history":[{"count":0,"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/posts\/176871\/revisions"}],"wp:attachment":[{"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/media?parent=176871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/categories?post=176871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/tags?post=176871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}