{"id":184291,"date":"2022-06-11T01:15:50","date_gmt":"2022-06-11T06:15:50","guid":{"rendered":"https:\/\/howtoremove.guide\/?p=184291"},"modified":"2022-06-11T01:15:55","modified_gmt":"2022-06-11T06:15:55","slug":"bbii-virus-fichier","status":"publish","type":"post","link":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/","title":{"rendered":"Bbii Virus"},"content":{"rendered":"\n<h2 id=\"bbii\" class=\"wp-block-heading\"><strong>Bbii<\/strong><\/h2>\n\n\n\n<p>Bbii est une menace en ligne que les cybercriminels utilisent pour crypter des fichiers num\u00e9riques et les retenir en otage contre une ran\u00e7on. Les sp\u00e9cialistes de la s\u00e9curit\u00e9 classent Bbii dans la cat\u00e9gorie des ransomwares car il est charg\u00e9 d&rsquo;extorquer de l&rsquo;argent aux internautes, institutions et entreprises ordinaires.<\/p>\n\n\n\n<p>Si votre ordinateur a \u00e9t\u00e9 infect\u00e9 par Bbii, Rrcc ou Eegf, cela signifie essentiellement que vos fichiers favoris sont d\u00e9sormais verrouill\u00e9s et qu&rsquo;une ran\u00e7on est demand\u00e9e pour les \u00ab\u00a0ouvrir\u00a0\u00bb \u00e0 nouveau. Si vous cherchez un moyen d&rsquo;\u00e9viter le paiement de cette ran\u00e7on, vous \u00eates sur la bonne page car nous avons pr\u00e9par\u00e9 un guide de suppression, un programme professionnel et des suggestions de r\u00e9cup\u00e9ration de fichiers qui peuvent vous aider \u00e0 supprimer Bbii et \u00e0 \u00e9conomiser votre argent.<\/p>\n\n\n\n<h2 id=\"le-virus-bbii\" class=\"wp-block-heading\"><strong>Le virus Bbii<\/strong><\/h2>\n\n\n\n<p>Le virus Bbii est un programme de type ransomware utilis\u00e9 pour extorquer de l&rsquo;argent. Les victimes du virus Bbii se voient g\u00e9n\u00e9ralement interdire l&rsquo;acc\u00e8s \u00e0 certains de leurs fichiers et sont invit\u00e9es \u00e0 payer une ran\u00e7on pour pouvoir y acc\u00e9der \u00e0 nouveau.<\/p>\n\n\n\n<p>Une fois \u00e0 l&rsquo;int\u00e9rieur d&rsquo;un ordinateur, Bbii peut commencer son terrible travail qui comprend une recherche approfondie de tous vos disques et lecteurs pour les fichiers que vous utilisez le plus fr\u00e9quemment. Apr\u00e8s les avoir d\u00e9tect\u00e9s, ce virus commence \u00e0 crypter ces fichiers un par un. D\u00e8s que le processus de cryptage est termin\u00e9, un message s&rsquo;affiche sur votre \u00e9cran pour vous informer que vous devrez payer une certaine somme d&rsquo;argent afin d&rsquo;inverser le cryptage appliqu\u00e9 et de pouvoir \u00e0 nouveau ouvrir et utiliser vos fichiers. Si vous payez, vous recevrez \u00e9ventuellement une cl\u00e9 de d\u00e9cryptage pour lib\u00e9rer vos fichiers, mais si vous ne le faites pas, les pirates derri\u00e8re Bbii vous menacent de perdre d\u00e9finitivement l&rsquo;acc\u00e8s \u00e0 vos donn\u00e9es.<\/p>\n\n\n\n<h2 id=\"la-recuperation-de-fichiers-bbii\" class=\"wp-block-heading\"><strong>La r\u00e9cup\u00e9ration de fichiers .Bbii<\/strong><\/h2>\n\n\n\n<p>La r\u00e9cup\u00e9ration du fichier .Bbii est un processus qui devrait aider les victimes du Bbii \u00e0 r\u00e9cup\u00e9rer leurs fichiers crypt\u00e9s. Cependant, la r\u00e9cup\u00e9ration du fichier .Bbii peut s&rsquo;av\u00e9rer difficile et ne peut \u00eatre garantie ni par le paiement d&rsquo;une ran\u00e7on ni par la suppression du ransomware.<\/p>\n\n\n\n<p>Peut-\u00eatre, apr\u00e8s avoir lu ceci, n&rsquo;avez-vous aucune id\u00e9e de ce qu&rsquo;il faut faire. Il est donc fortement recommand\u00e9 de bien peser toutes vos options. L&rsquo;une des fa\u00e7ons d&rsquo;essayer de r\u00e9soudre le probl\u00e8me sans rien payer est de supprimer Bbii \u00e0 l&rsquo;aide d&rsquo;un guide de suppression comme celui ci-dessous ou en utilisant un logiciel professionnel. D&rsquo;un autre c\u00f4t\u00e9, il n&rsquo;y a pas d&rsquo;assurance claire que vous r\u00e9cup\u00e9rerez vos fichiers m\u00eame si vous parvenez \u00e0 supprimer le virus avec une aide professionnelle. Enfin, donner son argent aux pirates n&rsquo;est pas non plus une bonne id\u00e9e. Les escrocs peuvent simplement prendre l&rsquo;argent et dispara\u00eetre sans vous envoyer de cl\u00e9 de d\u00e9cryptage et dans ce sc\u00e9nario, vous perdrez non seulement vos donn\u00e9es mais aussi votre argent.<\/p>\n\n\n\n<p>Par cons\u00e9quent, la sauvegarde de vos fichiers est la m\u00e9thode de s\u00e9curit\u00e9 la plus recommand\u00e9e. De cette fa\u00e7on, vous n&rsquo;aurez pas \u00e0 vous inqui\u00e9ter de la perte de vos donn\u00e9es importantes et vous n&rsquo;aurez qu&rsquo;\u00e0 supprimer le ransomware et \u00e0 recopier les fichiers n\u00e9cessaires sur l&rsquo;ordinateur propre. Bien entendu, veillez \u00e0 prot\u00e9ger le syst\u00e8me avec un logiciel de s\u00e9curit\u00e9 fiable. Ne sautez pas les mises \u00e0 jour logicielles et obtenez toujours les derni\u00e8res d\u00e9finitions de virus pour aider votre programme antivirus \u00e0 vous prot\u00e9ger efficacement contre les cybermenaces telles que le Bbii.<\/p>\n\n\n\n<p><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\"><strong>R\u00e9sum\u00e9:<\/strong><\/span><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><span style=\"font-family: helvetica, arial, sans-serif;\">Nom<\/span><\/td><td><span style=\"text-decoration: underline; font-family: helvetica, arial, sans-serif;\"><strong>Bbii<\/strong><\/span><\/td><\/tr><tr><td><span style=\"font-family: helvetica, arial, sans-serif;\">Type<\/span><\/td><td><span style=\"font-family: helvetica, arial, sans-serif;\"><em>Ransomware<\/em><\/span><\/td><\/tr><tr><td><span style=\"font-family: helvetica, arial, sans-serif;\">Outil de d\u00e9tection<\/span><\/td><td><div class='code-block code-block-13' style='margin: 8px 0; clear: both;'>\n<div><a class=\"banner\" href=\"https:\/\/howtoremove.guide\/download-pc-spyhunter-fr\/\" id=\"table_v2_fr\" style=\"display: block;text-underline: none; background: transparent; color: rgb(18, 133, 182);text-decoration:none\" target=\"_blank\"><span style=\"color:black\">Certaines menaces se r&eacute;installent d&#39;elles-m&ecirc;mes si vous ne supprimez pas leurs fichiers de base. Nous vous recommandons de t&eacute;l&eacute;charger SpyHunter pour supprimer les programmes nuisibles pour vous. <strong>Cela peut vous faire gagner des heures et vous &eacute;viter de nuire &agrave; votre syst&egrave;me en supprimant les mauvais fichiers.<\/strong><\/span><br \/>\n<strong style=\"font-weight:normal\"><strong><span style=\"font-size:14px\"><span style=\"background-color:#008fec; border-radius:5px; color:white; display:block; font-size:16px; margin:12px auto 12px auto; max-width:385px; padding:12px; text-align:center\">T&eacute;l&eacute;charger SpyHunter (Suppression Gratuite*)<\/span><\/span><\/strong><\/strong><\/a><strong style=\"font-weight:normal\"> <\/strong>\n<div class=\"col-lg-12\" style=\"padding:10px 30px 6px\"><span style=\"color:grey; font-size:11px; margin-bottom:4px; padding-right:30px; padding-top:10px\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" alt=\"\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2020\/06\/Offer-icon-1.svg\" style=\"height:12px; margin-right:4px; width:12px\" \/>OFFRE<\/span>&nbsp;<span style=\"font-size:11px\">*Suppression gratuite\/ vous permet, sous r&eacute;serve d&#39;une p&eacute;riode d&#39;attente de 48 heures, de proc&eacute;der &agrave; une correction et &agrave; une suppression pour les r&eacute;sultats trouv&eacute;s.&nbsp;Le CLUF de SpyHunter, la politique de confidentialit&eacute;<\/span><span style=\"color:#9a9a9a; font-size:11px; text-align:center\">&nbsp;et&nbsp;<\/span><a href=\"https:\/\/howtoremove.guide\/more-details-about-spyhunter-free-remover\/\" style=\"font-size: 11px; text-align: center;\">plus de d&eacute;tails sur Suppression Gratuite<\/a><span style=\"color:#9a9a9a; font-size:11px; text-align:center\">.<\/span><\/div>\n<strong style=\"font-weight:normal\"> <\/strong><\/div><\/div>\n<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 id=\"supprimer-bbii-ransomware\" class=\"western wp-block-heading\" id=\"Get_Rid_Of\"><span style=\"font-size: 14pt; color: #3b5998; font-family: helvetica, arial, sans-serif;\"><b>Supprimer Bbii Ransomware<\/b><\/span><\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png\" alt=\"Step1\" class=\"wp-image-6474\" title=\"Step1\"\/><\/figure>\n\n\n\n<p>Pour r\u00e9ussir \u00e0 supprimer un ransomware de votre ordinateur, vous devez suivre les instructions de cet article. Assurez-vous que tous les p\u00e9riph\u00e9riques de stockage externes et USB sont d\u00e9branch\u00e9s de la machine infect\u00e9e, et d\u00e9sactivez la connexion Internet de votre ordinateur pour emp\u00eacher le ransomware de se connecter \u00e0 ses serveurs malveillants.<br>Si vous mettez ce guide de suppression de Bbii dans vos favoris, vous pourrez y revenir en un clic et reprendre l\u00e0 o\u00f9 vous en \u00e9tiez apr\u00e8s le red\u00e9marrage de votre ordinateur.<\/p>\n\n\n\n<p>Nous vous recommandons \u00e9galement de suivre les instructions \u00e0 l&rsquo;\u00e9cran de <a href=\"https:\/\/howtoremove.guide\/how-to-enter-in-windows-safe-mode-all-versions\/\" target=\"_blank\" rel=\"noreferrer noopener\">ce lien<\/a> pour red\u00e9marrer votre ordinateur en mode sans \u00e9chec. Revenez ensuite \u00e0 cette page apr\u00e8s le red\u00e9marrage et passez \u00e0 l&rsquo;\u00e9tape suivante.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step2.png\" alt=\"Step2\" class=\"wp-image-6475\"\/><\/figure>\n\n\n\n<p><span style=\"font-family: helvetica, arial, sans-serif;\"><\/span><\/p>\n\n\n\n<p><span style=\"text-decoration: underline; color: #cd3028; font-family: helvetica, arial, sans-serif; font-size: 14pt;\"><strong><strong>ATTENTION! LIRE ATTENTIVEMENT AVANT DE PROCEDER!<\/strong><\/strong><\/span><\/p>\n\n\n\n<p><span style=\"font-family: helvetica, arial, sans-serif;\"><div class='code-block code-block-26' style='margin: 8px 0; clear: both;'>\n<div class=\"col_8 row\" id=\"firstguide_fr\">\n<div class=\"box-warning col-lg-12\" style=\"background:url(\/wp-content\/uploads\/2020\/02\/web-10.jpg)95px 6px no-repeat; margin-bottom:60px; margin-left:60px; margin-right:60px; margin-top:60px; padding-left:180px\">\n<p style=\"font-size:16px; text-align:left\">On nous pose souvent cette question, nous y r&eacute;pondons donc ici: La suppression manuelle du parasite peut prendre des heures et endommager votre syst&egrave;me au cours du processus. Nous vous recommandons de&nbsp;<a href=\"https:\/\/howtoremove.guide\/download-pc-spyhunter-fr\/\" style=\"color: #4138FF;\">t&eacute;l&eacute;charger SpyHunter<\/a>&nbsp;<span style=\"color:#2f5496\">pour voir s&#39;il peut d&eacute;tecter&nbsp;parasite&nbsp;sur votre machine.<\/span><\/p>\n<p style=\"color:#9a9a9a; font-size:10px; text-align:center\"><strong><a href=\"https:\/\/howtoremove.guide\/more-details-about-spyhunter-free-remover\/\" target=\"_blank\">Plus d&#39;informations sur&nbsp;SpyHunter<\/a>,&nbsp;les &eacute;tapes de d&eacute;sinstallation,&nbsp;le CLUF <\/strong><strong>&nbsp;et la politique de confidentialit&eacute;.<\/strong><\/p>\n<\/div>\n<\/div><\/div>\n<\/span><\/p>\n\n\n\n<p>Une fois la premi\u00e8re \u00e9tape termin\u00e9e, l&rsquo;ordinateur red\u00e9marre en mode sans \u00e9chec, puis va dans le Gestionnaire des t\u00e2ches (tapez Gestionnaire des t\u00e2ches dans le champ de recherche de Windows, puis appuyez sur Entr\u00e9e) et cliquez sur l&rsquo;onglet Processus. Triez les processus en cours d&rsquo;ex\u00e9cution en fonction de la m\u00e9moire et de l&rsquo;utilisation du processeur. Il est possible de voir les processus suspects, cliquez avec le bouton droit de la souris sur chacun d&rsquo;eux et s\u00e9lectionnez Ouvrir l&#8217;emplacement du fichier dans le menu contextuel, comme indiqu\u00e9 dans cette image, pour voir leurs fichiers :<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/05\/malware-start-taskbar.jpg\" alt=\"malware-start-taskbar\" title=\"Task Manager\"\/><\/figure>\n\n\n\n<p><span style=\"font-family: helvetica, arial, sans-serif;\"><span style=\"color: #333333;\"><span style=\"font-size: medium;\"><\/span><\/span><\/span><\/p>\n\n\n\n<p><span style=\"font-family: helvetica, arial, sans-serif; font-size: 12pt;\"><span style=\"color: #333333;\"><strong><span style=\"color: #333333;\"><b>Faites glisser et d\u00e9posez le contenu du dossier dans l&rsquo;analyseur ci-dessous pour lancer une v\u00e9rification et d\u00e9terminer s&rsquo;il y a des fichiers dangereux \u00e0 supprimer.<\/b><\/span><\/strong><\/span><\/span><\/p>\n\n\n\n<div class=\"vtas\"><div class=\"vtas__head\"><div class=\"vtas__head-title vtas__head-title_1 vtas__head-title_active\">Each file will be scanned with up to 64 antivirus programs to ensure maximum accuracy<\/div><div class=\"vtas__head-title vtas__head-title_2\">This scanner is free and will always remain free for our website's users.<\/div><\/div><div class=\"vtas__body\"><div class=\"vtas__not-matched\"><div class=\"vtas__not-matched-title\">This file is not matched with any known malware in the database. You can either do a full real-time scan of the file or skip it to upload a new file. Doing a full scan with 64 antivirus programs can take up to 3-4 minutes per file.<\/div><div class=\"vtas__not-matched-buttons\"><a href=\"javascript: void(0);\" class=\"vtas__not-matched-full-scan\">Full Scan<\/a><a href=\"javascript: void(0);\" class=\"vtas__not-matched-upload-new-file\">Upload New File<\/a><\/div><\/div><div class=\"vtas__dropzone clearfix\"><div class=\"vtas__dropzone-drag\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/plugins\/virustotal-api-shortcode\/\/static\/images\/files-icon 1.svg\" alt=\"Drag and Drop File Here To Scan\"><div class=\"vtas__dropzone-title\">Drag and Drop File Here To Scan<\/div><\/div><div class=\"vtas__dropzone-button-section\"><button class=\"vtas__dropzone-button\">Upload File<\/div><input type=\"file\" id=\"vtas-selectfile\" class=\"vtas__dropzone-input\"><\/div><div class=\"vtas__loading\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/plugins\/virustotal-api-shortcode\/\/static\/images\/ajax-loader 1.png\" alt=\"Loading\" class=\"vtas__loading-icon\"><div class=\"vtas__loading-title\">Analyzing <span class=\"vtas__loading-time\">0<\/span> s<\/div><\/div><\/div><div class=\"vtas__bottom\">Each file will be scanned with up to 64 antivirus programs to ensure maximum accuracy<\/div><ul class=\"vtas__results\"><\/ul><div class=\"vtas__privacy\">This scanner is based on VirusTotal's API. By submitting data to it, you agree to their <a href=\"https:\/\/support.virustotal.com\/hc\/en-us\/articles\/115002145529-Terms-of-Service\">Terms of Service<\/a> and <a href=\"https:\/\/support.virustotal.com\/hc\/en-us\/articles\/115002168385-Privacy-Policy\">Privacy Policy<\/a>, and to the sharing of your sample submission with the security community. Please do not submit files with personal information if you do not want them to be shared.<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Si l&rsquo;analyseur d\u00e9tecte des fichiers nuisibles qui doivent \u00eatre supprim\u00e9s, acc\u00e9dez d&rsquo;abord au processus auquel ils appartiennent, faites un clic droit dessus et choisissez \u00ab\u00a0Terminer le processus\u00a0\u00bb pour l&rsquo;arr\u00eater. Ensuite, acc\u00e9dez aux fichiers et supprimez-les.<\/p>\n\n\n\n<p>Ensuite, appuyez simultan\u00e9ment sur les touches Win et R de votre ordinateur pour saisir la commande suivante dans la bo\u00eete d&rsquo;ex\u00e9cution :<\/p>\n\n\n\n<div id=\"for-windows-98-xp-and-7\" dir=\"LTR\">\n<div id=\"for-windows-8-and-8-1\" dir=\"LTR\">\n<p style=\"text-align: justify;\" align=\"JUSTIFY\"><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>notepad %windir%\/system32\/Drivers\/etc\/hosts<\/strong><\/span><\/p>\n<p>Un fichier Hosts devrait s&rsquo;ouvrir \u00e0 l&rsquo;\u00e9cran. Toute adresse IP \u00e9trange trouv\u00e9e sous \u00ab\u00a0Localhost\u00a0\u00bb dans le texte doit \u00eatre signal\u00e9e dans la section des commentaires \u00e0 la fin de cette page. Les adresses IP que vous avez indiqu\u00e9es dans la section des commentaires seront examin\u00e9es de plus pr\u00e8s par nos soins et nous vous ferons savoir si elles sont dangereuses.<\/p>\n<figure><img wpfc-lazyload-disable=\"true\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3349 size-full\" title=\"Hosts file\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/07\/hosts_opt-1.png\" alt=\"hosts_opt (1)\" width=\"350\" height=\"185\" \/><\/figure>\n<p>Le volet de configuration du syst\u00e8me peut \u00e9galement contenir des fichiers li\u00e9s \u00e0 Bbii. Pour l&rsquo;ouvrir, cliquez sur le champ de recherche de Windows, entrez \u00ab\u00a0msconfig\u00a0\u00bb, puis appuyez sur Entr\u00e9e. Regardez la page \u00ab\u00a0d\u00e9marrage\u00a0\u00bb pour voir quels \u00e9l\u00e9ments de d\u00e9marrage ont \u00e9t\u00e9 coch\u00e9s.<\/p>\n<p>Tous les \u00e9l\u00e9ments de d\u00e9marrage associ\u00e9s au logiciel malveillant que vous devez d\u00e9sinstaller doivent \u00eatre d\u00e9coch\u00e9s. Toutefois, avant de proc\u00e9der \u00e0 des modifications, faites toujours des recherches en ligne si vous avez des doutes.<\/p>\n<div id=\"for-windows-98-xp-and-7\" dir=\"LTR\">\n<div id=\"for-windows-8-and-8-1\" dir=\"LTR\">\n<figure><img wpfc-lazyload-disable=\"true\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3262 size-full\" title=\"System Configuration\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/07\/msconfig_opt.png\" alt=\"msconfig_opt\" width=\"350\" height=\"233\" \/><\/figure>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\"><img wpfc-lazyload-disable=\"true\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6477 size-full\" title=\"Step4\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step4.png\" alt=\"Step4\" width=\"97\" height=\"24\" \/><\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\"><div class='code-block code-block-27' style='margin: 8px 0; clear: both;'>\n<div class=\"grey-bg\" id=\"secondguide_fr\" style=\"background:#fcfcfc url(\/wp-content\/uploads\/2020\/01\/web-11.png) 25px 65px no-repeat; box-shadow:4px 10px 8px -6px rgba(239, 239, 239, 0.9); margin-bottom:25px; padding:20px 20px 20px 130px; position:relative; text-align:left\">\n<p style=\"font-size:16px; margin-bottom:30px; margin-top:0px\">Pour que vous supprimiez le <strong>parasite<\/strong> vous-m&ecirc;me, vous devrez peut-&ecirc;tre vous occuper des fichiers syst&egrave;me et des registres. <span style=\"font-size:12.0pt\"><span style=\"line-height:107%\"><span> <\/span><\/span><\/span><span style=\"color:#2f5496\">Si vous devez faire cela, soyez extr&ecirc;mement prudent, car vous pourriez endommager votre syst&egrave;me.<\/span><\/p>\n<p style=\"font-size:16px; margin-bottom:30px; margin-top:0px\"><span style=\"color:#2f5496\">Si vous voulez &eacute;viter le risque, nous vous recommandons de <a href=\"https:\/\/howtoremove.guide\/download-pc-spyhunter-fr\/\">t&eacute;l&eacute;charger SpyHunter<\/a>, un outil professionnel de suppression de logiciels malveillants.<\/span><\/p>\n<p style=\"color:#9a9a9a; font-size:10px; text-align:center\"><strong><a href=\"https:\/\/howtoremove.guide\/more-details-about-spyhunter-free-remover\/\" target=\"_blank\">Plus d&#39;informations sur&nbsp;SpyHunter<\/a>,&nbsp;les &eacute;tapes de d&eacute;sinstallation,&nbsp;le CLUF <\/strong><strong>&nbsp;et la politique de confidentialit&eacute;.<\/strong><\/p>\n<\/div><\/div>\n\n<p>Un logiciel malveillant comme Bbii peut se cacher longtemps dans le registre gr\u00e2ce aux fichiers malveillants qu&rsquo;il y ajoute silencieusement. C&rsquo;est pourquoi vous devez examiner minutieusement le registre \u00e0 la recherche de fichiers li\u00e9s \u00e0 Bbii qui doivent \u00eatre supprim\u00e9s afin d&rsquo;\u00e9viter que le danger ne r\u00e9apparaisse au red\u00e9marrage du syst\u00e8me. Pour ouvrir l&rsquo;\u00e9diteur du registre, tapez Regedit dans le champ de recherche de Windows et appuyez sur la touche Entr\u00e9e du clavier.<\/p>\n<p>Les touches CTRL et F de votre ordinateur peuvent \u00eatre utilis\u00e9es pour rechercher dans l&rsquo;\u00e9diteur de registre les fichiers infect\u00e9s, qui peuvent ensuite \u00eatre supprim\u00e9s. Commencez la recherche en tapant le nom du ransomware dans le champ Rechercher, puis s\u00e9lectionnez Rechercher suivant pour lancer la recherche.<\/p>\n<p>Attention ! Il est possible qu&rsquo;un utilisateur inexp\u00e9riment\u00e9 ait des difficult\u00e9s \u00e0 d\u00e9couvrir et \u00e0 supprimer les fichiers li\u00e9s au ransomware dans le registre. Il y a un risque d&rsquo;endommager le syst\u00e8me et d&rsquo;affecter sa stabilit\u00e9 si les entr\u00e9es du registre sont supprim\u00e9es \u00e0 tort. Si vous ne pensez pas \u00eatre \u00e0 la hauteur de la t\u00e2che, vous voudrez probablement utiliser un programme de suppression de virus comme celui de cette page.<\/p>\n<p>Les fichiers li\u00e9s au ransomware peuvent \u00e9galement se trouver dans les emplacements syst\u00e8me suivants. Pour les v\u00e9rifier, tapez les termes de recherche suivants dans la bo\u00eete de recherche Windows et appuyez sur Entr\u00e9e pour les ouvrir :<\/p>\n<ol>\n<li><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>%AppData%<\/strong><\/span><\/li>\n<li><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>%LocalAppData%<\/strong><\/span><\/li>\n<li><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>%ProgramData%<\/strong><\/span><\/li>\n<li><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>%WinDir%<\/strong><\/span><\/li>\n<li><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>%Temp%<\/strong><\/span><\/li>\n<\/ol>\n<p>Recherchez dans chacun des emplacements des fichiers et des dossiers aux noms al\u00e9atoires et si un \u00e9l\u00e9ment retient votre attention, faites une recherche en ligne pour savoir s&rsquo;il doit vraiment \u00eatre supprim\u00e9. Vous pouvez \u00e9galement supprimer toutes les donn\u00e9es temporaires en s\u00e9lectionnant tout ce qui se trouve dans le dossier Temp de votre ordinateur, puis en appuyant sur la touche de suppression de votre clavier.<\/p>\n<p><img wpfc-lazyload-disable=\"true\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6478 size-full\" title=\"Step 5\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step5.png\" alt=\"Step5\" width=\"97\" height=\"24\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Comment d\u00e9crypter les fichiers Bbii<\/strong><\/p>\n<p>M\u00eame les experts en d\u00e9cryptage de ransomware les plus chevronn\u00e9s peuvent avoir du mal \u00e0 d\u00e9crypter les donn\u00e9es chiffr\u00e9es par un ransomware dans certains cas. Par cons\u00e9quent, les utilisateurs inexp\u00e9riment\u00e9s peuvent avoir du mal \u00e0 faire face \u00e0 un ransomware, car les diff\u00e9rentes versions du ransomware peuvent utiliser diff\u00e9rents algorithmes de d\u00e9cryptage de fichiers dont l&rsquo;efficacit\u00e9 est variable. La premi\u00e8re \u00e9tape pour faire face \u00e0 une attaque de ransomware consiste \u00e0 d\u00e9terminer la variante \u00e0 laquelle vous avez affaire. Les extensions de fichier des fichiers crypt\u00e9s peuvent vous aider \u00e0 trouver cette information.<\/p>\n<p>N&rsquo;oubliez pas que si le ransomware est toujours pr\u00e9sent sur votre ordinateur, il cryptera toutes les donn\u00e9es que vous pourrez restaurer. C&rsquo;est pourquoi une v\u00e9rification compl\u00e8te du PC est n\u00e9cessaire avant d&rsquo;entamer toute proc\u00e9dure de r\u00e9cup\u00e9ration des donn\u00e9es. C&rsquo;est \u00e0 ce moment-l\u00e0 qu&rsquo;un logiciel anti-malware s&rsquo;av\u00e8re utile.<\/p>\n<p><strong>Nouveau Djvu Ransomware<\/strong><\/p>\n<p>STOP Djvu est une version du ransomware qui cause beaucoup de probl\u00e8mes sur un certain nombre de syst\u00e8mes et demande une ran\u00e7on aux victimes en \u00e9change du d\u00e9cryptage de leurs donn\u00e9es. Les fichiers chiffr\u00e9s se terminent souvent par .Bbii, ce qui indique la variante sp\u00e9cifique du ransomware qui a infect\u00e9 votre syst\u00e8me. Pour les personnes qui ont v\u00e9rifi\u00e9 que leur PC n&rsquo;est pas infect\u00e9 par un malware, le d\u00e9cryptage peut \u00eatre possible \u00e0 l&rsquo;aide d&rsquo;un programme de d\u00e9cryptage tel que celui li\u00e9 ci-dessous :\u00a0<\/p>\n<p><a href=\"https:\/\/www.emsisoft.com\/ransomware-decryption-tools\/stop-djvu\" target=\"_blank\" rel=\"noopener\">https:\/\/www.emsisoft.com\/ransomware-decryption-tools\/stop-djvu<\/a><\/p>\n<p>Le contrat de licence et toutes les instructions associ\u00e9es au d\u00e9crypteur doivent \u00eatre soigneusement examin\u00e9s avant le d\u00e9cryptage. Si vos fichiers ont \u00e9t\u00e9 crypt\u00e9s \u00e0 l&rsquo;aide d&rsquo;une cl\u00e9 hors ligne inconnue ou d&rsquo;un cryptage en ligne, la capacit\u00e9 de ce logiciel \u00e0 les d\u00e9coder n&rsquo;est pas garantie, gardez cela \u00e0 l&rsquo;esprit.<\/p>\n<p>Un logiciel antivirus peut \u00eatre n\u00e9cessaire si les \u00e9tapes manuelles d\u00e9crites sur cette page ne permettent pas de supprimer compl\u00e8tement Bbii. Vous pouvez v\u00e9rifier manuellement n&rsquo;importe quel fichier avec notre <a href=\"https:\/\/howtoremove.guide\/online-virus-scanner\/\" target=\"_blank\" rel=\"noopener\">antivirus en ligne gratuit<\/a> si vous vous inqui\u00e9tez de sa s\u00e9curit\u00e9. Si vous avez des questions concernant ces instructions de suppression, n&rsquo;h\u00e9sitez pas \u00e0 poster un commentaire ci-dessous et notre \u00e9quipe fera de son mieux pour vous r\u00e9pondre rapidement.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bbii Bbii est une menace en ligne que les cybercriminels utilisent pour crypter des fichiers num\u00e9riques et les retenir en otage contre une ran\u00e7on. Les sp\u00e9cialistes de la s\u00e9curit\u00e9 classent Bbii dans la cat\u00e9gorie des ransomwares car il est charg\u00e9 d&rsquo;extorquer de l&rsquo;argent aux internautes, institutions et entreprises ordinaires. Si votre ordinateur a \u00e9t\u00e9 infect\u00e9 [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[244],"tags":[],"class_list":["post-184291","post","type-post","status-publish","format-standard","hentry","category-ransomware-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bbii Virus Ransomware (.bbii) Suppression et D\u00e9cryptage des Fichiers<\/title>\n<meta name=\"description\" content=\"Bbii est une menace en ligne que les cybercriminels utilisent pour crypter des fichiers num\u00e9riques et les retenir en otage contre une ran\u00e7on.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bbii Virus Ransomware (.bbii) Suppression et D\u00e9cryptage des Fichiers\" \/>\n<meta property=\"og:description\" content=\"Bbii est une menace en ligne que les cybercriminels utilisent pour crypter des fichiers num\u00e9riques et les retenir en otage contre une ran\u00e7on.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/\" \/>\n<meta property=\"og:site_name\" content=\"HowToRemove.Guide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/howtoremove.guide\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-11T06:15:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-11T06:15:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png\" \/>\n<meta name=\"author\" content=\"George Slaine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GuideBasics\" \/>\n<meta name=\"twitter:site\" content=\"@GuideBasics\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Slaine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bbii Virus Ransomware (.bbii) Suppression et D\u00e9cryptage des Fichiers","description":"Bbii est une menace en ligne que les cybercriminels utilisent pour crypter des fichiers num\u00e9riques et les retenir en otage contre une ran\u00e7on.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/","og_locale":"fr_FR","og_type":"article","og_title":"Bbii Virus Ransomware (.bbii) Suppression et D\u00e9cryptage des Fichiers","og_description":"Bbii est une menace en ligne que les cybercriminels utilisent pour crypter des fichiers num\u00e9riques et les retenir en otage contre une ran\u00e7on.","og_url":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/","og_site_name":"HowToRemove.Guide","article_publisher":"https:\/\/www.facebook.com\/howtoremove.guide","article_published_time":"2022-06-11T06:15:50+00:00","article_modified_time":"2022-06-11T06:15:55+00:00","og_image":[{"url":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","type":"","width":"","height":""}],"author":"George Slaine","twitter_card":"summary_large_image","twitter_creator":"@GuideBasics","twitter_site":"@GuideBasics","twitter_misc":{"\u00c9crit par":"George Slaine","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/#article","isPartOf":{"@id":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/"},"author":{"name":"George Slaine","@id":"https:\/\/howtoremove.guide\/fr\/#\/schema\/person\/21c82db8a1f4d7cf888c5c02c079d8d8"},"headline":"Bbii Virus","datePublished":"2022-06-11T06:15:50+00:00","dateModified":"2022-06-11T06:15:55+00:00","mainEntityOfPage":{"@id":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/"},"wordCount":1911,"commentCount":0,"publisher":{"@id":"https:\/\/howtoremove.guide\/fr\/#organization"},"image":{"@id":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/#primaryimage"},"thumbnailUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","articleSection":["Ransomware fr"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/","url":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/","name":"Bbii Virus Ransomware (.bbii) Suppression et D\u00e9cryptage des Fichiers","isPartOf":{"@id":"https:\/\/howtoremove.guide\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/#primaryimage"},"image":{"@id":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/#primaryimage"},"thumbnailUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","datePublished":"2022-06-11T06:15:50+00:00","dateModified":"2022-06-11T06:15:55+00:00","description":"Bbii est une menace en ligne que les cybercriminels utilisent pour crypter des fichiers num\u00e9riques et les retenir en otage contre une ran\u00e7on.","breadcrumb":{"@id":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/#primaryimage","url":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","contentUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/howtoremove.guide\/fr\/bbii-virus-fichier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/howtoremove.guide\/fr\/"},{"@type":"ListItem","position":2,"name":"Ransomware fr","item":"https:\/\/howtoremove.guide\/fr\/category\/ransomware-fr\/"},{"@type":"ListItem","position":3,"name":"Bbii Virus"}]},{"@type":"WebSite","@id":"https:\/\/howtoremove.guide\/fr\/#website","url":"https:\/\/howtoremove.guide\/fr\/","name":"HowToRemove.Guide","description":"Virus &amp; Malware Removal","publisher":{"@id":"https:\/\/howtoremove.guide\/fr\/#organization"},"alternateName":"HowToRemove.guide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/howtoremove.guide\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/howtoremove.guide\/fr\/#organization","name":"HowToRemove.Guide","url":"https:\/\/howtoremove.guide\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/howtoremove.guide\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2018\/09\/howtoremove-logo-250-px.png","contentUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2018\/09\/howtoremove-logo-250-px.png","width":250,"height":42,"caption":"HowToRemove.Guide"},"image":{"@id":"https:\/\/howtoremove.guide\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/howtoremove.guide","https:\/\/x.com\/GuideBasics","https:\/\/www.youtube.com\/channel\/UCb61rHhYyMKutbMLc5r6w-w"]},{"@type":"Person","@id":"https:\/\/howtoremove.guide\/fr\/#\/schema\/person\/21c82db8a1f4d7cf888c5c02c079d8d8","name":"George Slaine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/howtoremove.guide\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/17047dcdf6307b0bc9558fc516840e6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17047dcdf6307b0bc9558fc516840e6c?s=96&d=mm&r=g","caption":"George Slaine"},"url":"https:\/\/howtoremove.guide\/fr\/author\/georges\/"}]}},"spectra_custom_meta":{"_edit_lock":["1654928158:15"],"VirusName":["Bbii"],"_edit_last":["15"],"_single_add_custom_css":[""],"_vce_meta":["a:4:{s:11:\"use_sidebar\";s:7:\"inherit\";s:7:\"sidebar\";s:7:\"inherit\";s:14:\"sticky_sidebar\";s:7:\"inherit\";s:6:\"layout\";s:7:\"inherit\";}"],"_yoast_wpseo_primary_category":["244"],"_yoast_wpseo_title":["Bbii Virus Ransomware (.bbii) Suppression et D\u00e9cryptage des Fichiers %%page%%"],"_yoast_wpseo_metadesc":["Bbii est une menace en ligne que les cybercriminels utilisent pour crypter des fichiers num\u00e9riques et les retenir en otage contre une ran\u00e7on."],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":["9"],"_uag_page_assets":["a:9:{s:3:\"css\";s:4944:\".wp-block-uagb-separator{text-align:center;box-sizing:border-box;line-height:0}.wp-block-uagb-separator__inner{display:inline-block}.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner{display:flex;justify-content:center;align-items:center;margin:0 auto}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::before,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::after,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::after{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--icon .wp-block-uagb-separator-element svg{font-size:30px;color:#333;fill:#333;width:30px;height:30px;line-height:30px;max-width:none}.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{word-break:initial;margin:0}\n.uagb-block-9f7858eb.wp-block-uagb-separator{text-align: center;}.uagb-block-9f7858eb.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-9f7858eb.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 90%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}@media only screen and (max-width: 976px) {.uagb-block-9f7858eb.wp-block-uagb-separator{text-align: center;}.uagb-block-9f7858eb.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-9f7858eb.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}@media only screen and (max-width: 767px) {.uagb-block-9f7858eb.wp-block-uagb-separator{text-align: center;}.uagb-block-9f7858eb.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-9f7858eb.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}.uagb-block-f3a675c7.wp-block-uagb-separator{text-align: center;}.uagb-block-f3a675c7.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-f3a675c7.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 90%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}@media only screen and (max-width: 976px) {.uagb-block-f3a675c7.wp-block-uagb-separator{text-align: center;}.uagb-block-f3a675c7.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-f3a675c7.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}@media only screen and (max-width: 767px) {.uagb-block-f3a675c7.wp-block-uagb-separator{text-align: center;}.uagb-block-f3a675c7.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-f3a675c7.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:33:{i:0;s:10:\"core\/group\";i:2;s:10:\"core\/image\";i:4;s:15:\"core\/navigation\";i:5;s:14:\"uagb\/separator\";i:7;s:15:\"core\/post-title\";i:9;s:16:\"core\/post-author\";i:10;s:14:\"core\/paragraph\";i:11;s:14:\"core\/post-date\";i:12;s:15:\"core\/post-terms\";i:15;s:24:\"core\/post-featured-image\";i:16;s:17:\"core\/post-content\";i:17;s:14:\"core\/separator\";i:19;s:13:\"core\/comments\";i:20;s:19:\"core\/comments-title\";i:21;s:21:\"core\/comment-template\";i:24;s:11:\"core\/avatar\";i:26;s:24:\"core\/comment-author-name\";i:28;s:17:\"core\/comment-date\";i:29;s:22:\"core\/comment-edit-link\";i:30;s:20:\"core\/comment-content\";i:31;s:23:\"core\/comment-reply-link\";i:32;s:24:\"core\/comments-pagination\";i:33;s:33:\"core\/comments-pagination-previous\";i:34;s:32:\"core\/comments-pagination-numbers\";i:35;s:29:\"core\/comments-pagination-next\";i:36;s:23:\"core\/post-comments-form\";i:38;s:12:\"core\/columns\";i:39;s:11:\"core\/column\";i:40;s:22:\"wpml\/language-switcher\";i:41;s:15:\"core\/site-title\";i:42;s:12:\"core\/heading\";i:43;s:10:\"core\/table\";i:44;s:22:\"tadv\/classic-paragraph\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1784059105;s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"rank_math_primary_category":["244"],"rank_math_title":["Bbii Virus Ransomware (.bbii) Suppression et D\u00e9cryptage des Fichiers %page%"],"rank_math_description":["Bbii est une menace en ligne que les cybercriminels utilisent pour crypter des fichiers num\u00e9riques et les retenir en otage contre une ran\u00e7on."],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"litespeed_vpi_list":["a:1:{i:0;s:24:\"howtoremove-new-logo.png\";}"],"_uag_css_file_name":["uag-css-184291.css"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"George Slaine","author_link":"https:\/\/howtoremove.guide\/fr\/author\/georges\/"},"uagb_comment_info":0,"uagb_excerpt":"Bbii Bbii est une menace en ligne que les cybercriminels utilisent pour crypter des fichiers num\u00e9riques et les retenir en otage contre une ran\u00e7on. Les sp\u00e9cialistes de la s\u00e9curit\u00e9 classent Bbii dans la cat\u00e9gorie des ransomwares car il est charg\u00e9 d&rsquo;extorquer de l&rsquo;argent aux internautes, institutions et entreprises ordinaires. Si votre ordinateur a \u00e9t\u00e9 infect\u00e9\u2026","_links":{"self":[{"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/posts\/184291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/comments?post=184291"}],"version-history":[{"count":0,"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/posts\/184291\/revisions"}],"wp:attachment":[{"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/media?parent=184291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/categories?post=184291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtoremove.guide\/fr\/wp-json\/wp\/v2\/tags?post=184291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}