{"id":189981,"date":"2022-11-12T16:36:08","date_gmt":"2022-11-12T21:36:08","guid":{"rendered":"https:\/\/howtoremove.guide\/?p=189981"},"modified":"2022-11-12T16:36:13","modified_gmt":"2022-11-12T21:36:13","slug":"rimuovere-fate-virus","status":"publish","type":"post","link":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/","title":{"rendered":"Fate Virus"},"content":{"rendered":"\n<h2 id=\"fate\" class=\"wp-block-heading\"><strong>Fate<\/strong><\/h2>\n\n\n\n<p>Fate \u00e8 un rappresentante del gruppo di cryptovirus Ransomware che prende di mira diversi computer per criptare i file in essi memorizzati. I criminali informatici che si celano dietro Fate lo utilizzano per chiedere un riscatto alle loro vittime in cambio della fornitura di una chiave di decriptazione dei file.<\/p>\n\n\n\n<p>Il nostro team di &#8220;How to remove&#8221; ha dedicato questo articolo a questa famigerata infezione e far\u00e0 tutto il possibile per aiutarvi a rimuoverla nel modo pi\u00f9 rapido e sicuro possibile. Tuttavia, per riuscire a individuare e rimuovere il ransomware, dovrete seguire attentamente i passaggi della guida che abbiamo pubblicato di seguito. Il recupero dei file criptati potrebbe richiedere alcune istruzioni aggiuntive e, sebbene non possiamo garantire che seguendo i passaggi descritti tutto torner\u00e0 alla normalit\u00e0, crediamo comunque che fare un tentativo non faccia male. Per questo motivo vi suggeriamo di dedicare qualche minuto alla revisione di questo materiale.<\/p>\n\n\n\n<h2 id=\"il-virus-fate\" class=\"wp-block-heading\"><strong>Il virus Fate<\/strong><\/h2>\n\n\n\n<p>Il virus Fate \u00e8 una pericolosa infezione ransomware che viene utilizzata per impedire agli utenti di accedere a vari tipi di informazioni digitali memorizzate sui loro computer. La rimozione del virus Fate pu\u00f2 essere complicata e spesso richiede l&#8217;assistenza di un software professionale.<\/p>\n\n\n\n<p>Il ricatto \u00e8 stato un modo comune per ottenere denaro veloce e i truffatori online e offline lo hanno utilizzato per molti anni. Al giorno d&#8217;oggi, tuttavia, la tecnologia digitale apre agli hacker nuove strade per molestare gli utenti del web e questi ne traggono pieno vantaggio. Questi criminali informatici utilizzano le minacce Ransomware per limitare l&#8217;accesso a informazioni preziose memorizzate su un determinato computer, al fine di ricattare il proprietario per ottenere un riscatto. Fate, Zatp e Fatp sono esempi tipici di tali minacce che utilizzano uno speciale algoritmo di crittografia dei file per &#8220;proteggere&#8221; i file degli utenti e renderli inaccessibili senza una chiave di decrittazione appositamente generata. Le vittime di questo Ransomware sono tenute a pagare una somma di denaro per la chiave di decrittazione in possesso degli hacker. Molte persone, tuttavia, cercano modi alternativi per rimuovere l&#8217;infezione e decodificare i propri file senza inviare denaro ai truffatori online.<\/p>\n\n\n\n<h2 id=\"la-crittografia-dei-file-fate\" class=\"wp-block-heading\"><strong>La crittografia dei file Fate<\/strong><\/h2>\n\n\n\n<p>La crittografia dei file Fate \u00e8 un algoritmo complesso e molto difficile da decodificare che viene utilizzato per rendere inaccessibili i file degli utenti. Gli utenti che hanno bisogno di accedere ai propri file possono liberarli dalla crittografia Fate solo dopo aver pagato una chiave di decrittazione e averla applicata.<\/p>\n\n\n\n<p>Le vittime di Fate di solito trovano un messaggio di testo sul loro computer con le istruzioni su come trasferire il denaro richiesto. Purtroppo, ci sono casi in cui gli utenti pagano il riscatto e non ricevono mai la chiave di decriptazione. Naturalmente, ci sono casi in cui gli hacker inviano una chiave alle loro vittime, ma non si pu\u00f2 mai essere sicuri se riuscir\u00e0 o meno a invertire la crittografia applicata. Per questo motivo \u00e8 generalmente una cattiva idea rischiare il proprio denaro per arricchire i truffatori. Ma non tutto \u00e8 perduto: nella guida alla rimozione qui sotto vi forniamo i passaggi e gli screenshot su come rimuovere il ransomware e alcuni suggerimenti gratuiti per il recupero dei file che potrebbero funzionare se li provate. Vi invitiamo inoltre a controllare il nostro elenco di decrittatori gratuiti e a cercare un aiuto professionale per avere maggiori possibilit\u00e0 di gestire l&#8217;infezione nel miglior modo possibile.<\/p>\n\n\n\n<h3 id=\"sommario\" class=\"wp-block-heading\"><strong>SOMMARIO:<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Nome<\/td><td><span style=\"text-decoration: underline; font-family: helvetica, arial, sans-serif;\"><strong><strong><strong><strong><strong>Fate<\/strong><\/strong><\/strong><\/strong><\/strong><\/span><\/td><\/tr><tr><td>Tipo<\/td><td>Ransomware<\/td><\/tr><tr><td>Strumento di Analisi<\/td><td><div class='code-block code-block-17' style='margin: 8px 0; clear: both;'>\n<div class=\"grey-bg\" id=\"secondguide_it\" style=\"background:#fcfcfc url(\/wp-content\/uploads\/2020\/01\/web-11.png) 25px 65px no-repeat; box-shadow:4px 10px 8px -6px rgba(239, 239, 239, 0.9); margin-bottom:25px; padding:20px 20px 20px 130px; position:relative; text-align:left\">\n<p style=\"font-size:16px; margin-bottom:30px; margin-top:0px\">Per rimuovere <strong>parasite<\/strong> da soli, potreste dover toccare I file del sistema e I registri. <span style=\"font-size:12.0pt\"><span style=\"line-height:107%\"><span> <\/span><\/span><\/span><span style=\"color:#2f5496\">Se doveste farlo, dovrete essere estremamente attenti perch&eacute; potreste danneggiare il vostro sistema.<\/span><\/p>\n<p style=\"font-size:16px; margin-bottom:30px; margin-top:0px\"><span style=\"color:#2f5496\">Se volete evitare il rischio, raccomandiamo di <a href=\"https:\/\/howtoremove.guide\/download-pc-spyhunter-it\/\">scaricare SpyHunter<\/a>, un tool professionale per la rimozione dei malware.<\/span><\/p>\n<p style=\"color:#9a9a9a; font-size:10px; text-align:center\">&nbsp;<\/p>\n<\/div><\/div>\n<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 id=\"rimuovere-fate-ransomware\" class=\"western wp-block-heading\" id=\"Get_Rid_Of\"><span style=\"font-size: 14pt; color: #3b5998; font-family: helvetica, arial, sans-serif;\"><b><strong>Rimuovere Fate Ransomware<\/strong><\/b><\/span><\/h2>\n\n\n\n<p>Avete a che fare con un&#8217;infezione ransomware che pu\u00f2 ripristinarsi da sola se non si rimuovono i suoi file principali. Di seguito troverete una guida alla rimozione che contiene istruzioni approfondite su come:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Individuare ed eseguire la scansione dei processi dannosi nel task manager.<\/li><li>Identificare nel pannello di controllo tutti i programmi installati con il malware e come rimuoverli. Search Marquis \u00e8 un hijacker di alto profilo che viene installato con molti malware.<\/li><li>Come decifrare e recuperare i file crittografati (se attualmente \u00e8 possibile).<\/li><\/ol>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png\" alt=\"Step1\" class=\"wp-image-6474\" title=\"Step1\"\/><\/figure>\n\n\n\n<p class=\"western\"><span style=\"font-family: helvetica, arial, sans-serif;\"><\/span><\/p>\n\n\n\n<p>Subito dopo un attacco ransomware, \u00e8 necessario fare tutto il possibile per liberarsi del malware e questa guida vi insegner\u00e0 come. La prima cosa da fare \u00e8 scollegare eventuali unit\u00e0 flash, dischi rigidi esterni o altre periferiche. Quindi, scollegate il computer da Internet per evitare che il ransomware riceva aggiornamenti dai suoi server.<\/p>\n\n\n\n<p>Inserite questa pagina tra i preferiti del vostro browser, in modo da potervi tornare facilmente se il computer richiede un riavvio durante uno dei passaggi di questa guida.<\/p>\n\n\n\n<p>Per assicurarsi che il resto del processo di rimozione avvenga senza intoppi, \u00e8 necessario riavviare il computer infetto in modalit\u00e0 provvisoria. Accedere alla modalit\u00e0 provvisoria seguendo i passaggi descritti in <a href=\"https:\/\/howtoremove.guide\/how-to-enter-in-windows-safe-mode-all-versions\/\" target=\"_blank\" rel=\"noreferrer noopener\">questo link<\/a>. Dopo il riavvio del computer, \u00e8 possibile tornare qui e continuare con le istruzioni.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step2.png\" alt=\"Step2\" class=\"wp-image-6475\"\/><\/figure>\n\n\n\n<p><span style=\"font-family: helvetica, arial, sans-serif;\"><\/span><\/p>\n\n\n\n<p><span style=\"text-decoration: underline; color: #cd3028; font-family: helvetica, arial, sans-serif; font-size: 14pt;\"><strong><strong><u>ATTENZIONE! LEGGERE CON ATTENZIONE PRIMA DI PROCEDERE!<\/u><\/strong><\/strong><\/span><\/p>\n\n\n\n<p><span style=\"font-family: helvetica, arial, sans-serif;\"><div class='code-block code-block-30' style='margin: 8px 0; clear: both;'>\n<div class=\"col_8 row\" id=\"firstguide_it\">\n<div class=\"box-warning col-lg-12\" style=\"background:url(\/wp-content\/uploads\/2020\/02\/web-10.jpg)95px 6px no-repeat; margin-bottom:60px; margin-left:60px; margin-right:60px; margin-top:60px; padding-left:180px\">\n<p style=\"font-size:16px; text-align:left\">Questo ci viene chiesto spesso, quindi lo scriviamo qui: Per rimuovere parasite manualmente ci vogliono ore e potrebbe nel frattempo danneggiare il vostro sistema. Raccomandiamo di de&nbsp;<a href=\"https:\/\/howtoremove.guide\/download-pc-spyhunter-it\/\" style=\"color: #4138FF;\">scaricare SpyHunter<\/a>&nbsp;<span style=\"color:#2f5496\">per vedere se pu&ograve; individuare I file del virus al posto vostro.<\/span><\/p>\n<\/div>\n<\/div><\/div>\n<\/span><\/p>\n\n\n\n<p>Sul computer infetto, aprire il Task Manager premendo contemporaneamente Ctrl+Shift+ESC. Quindi, selezionare la scheda Processi dalle schede disponibili nella parte superiore dello schermo. Cercare i processi con nomi strani, ordinando tutti i processi in base alla memoria e all&#8217;uso della CPU.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/05\/malware-start-taskbar.jpg\" alt=\"malware-start-taskbar\" title=\"Task Manager\"\/><\/figure>\n\n\n\n<p><span style=\"font-family: helvetica, arial, sans-serif;\"><span style=\"color: #333333;\"><span style=\"font-size: medium;\"><\/span><\/span><\/span><\/p>\n\n\n\n<p><span style=\"font-family: helvetica, arial, sans-serif; font-size: 12pt;\"><span style=\"color: #333333;\"><strong><span style=\"color: #333333;\"><b>Quindi, fare clic con il pulsante destro del mouse sul processo discutibile e scegliere Apri posizione file per visualizzare i file associati. Potete usare lo scanner antivirus qui sotto per assicurarvi che questi file siano sicuri da conservare.<\/b><\/span><\/strong><\/span><\/span><\/p>\n\n\n\n<div class=\"vtas\"><div class=\"vtas__head\"><div class=\"vtas__head-title vtas__head-title_1 vtas__head-title_active\">Each file will be scanned with up to 64 antivirus programs to ensure maximum accuracy<\/div><div class=\"vtas__head-title vtas__head-title_2\">This scanner is free and will always remain free for our website's users.<\/div><\/div><div class=\"vtas__body\"><div class=\"vtas__not-matched\"><div class=\"vtas__not-matched-title\">This file is not matched with any known malware in the database. You can either do a full real-time scan of the file or skip it to upload a new file. Doing a full scan with 64 antivirus programs can take up to 3-4 minutes per file.<\/div><div class=\"vtas__not-matched-buttons\"><a href=\"javascript: void(0);\" class=\"vtas__not-matched-full-scan\">Full Scan<\/a><a href=\"javascript: void(0);\" class=\"vtas__not-matched-upload-new-file\">Upload New File<\/a><\/div><\/div><div class=\"vtas__dropzone clearfix\"><div class=\"vtas__dropzone-drag\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/plugins\/virustotal-api-shortcode\/\/static\/images\/files-icon 1.svg\" alt=\"Drag and Drop File Here To Scan\"><div class=\"vtas__dropzone-title\">Drag and Drop File Here To Scan<\/div><\/div><div class=\"vtas__dropzone-button-section\"><button class=\"vtas__dropzone-button\">Upload File<\/div><input type=\"file\" id=\"vtas-selectfile\" class=\"vtas__dropzone-input\"><\/div><div class=\"vtas__loading\"><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/howtoremove.guide\/wp-content\/plugins\/virustotal-api-shortcode\/\/static\/images\/ajax-loader 1.png\" alt=\"Loading\" class=\"vtas__loading-icon\"><div class=\"vtas__loading-title\">Analyzing <span class=\"vtas__loading-time\">0<\/span> s<\/div><\/div><\/div><div class=\"vtas__bottom\">Each file will be scanned with up to 64 antivirus programs to ensure maximum accuracy<\/div><ul class=\"vtas__results\"><\/ul><div class=\"vtas__privacy\">This scanner is based on VirusTotal's API. By submitting data to it, you agree to their <a href=\"https:\/\/support.virustotal.com\/hc\/en-us\/articles\/115002145529-Terms-of-Service\">Terms of Service<\/a> and <a href=\"https:\/\/support.virustotal.com\/hc\/en-us\/articles\/115002168385-Privacy-Policy\">Privacy Policy<\/a>, and to the sharing of your sample submission with the security community. Please do not submit files with personal information if you do not want them to be shared.<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p>Se nella cartella sono state rilevate minacce, il processo in corso deve essere interrotto facendo clic con il pulsante destro del mouse sulla scheda Processi e scegliendo Termina processo. Tornare alla cartella Percorso file in cui la scansione ha rilevato i file scoperti ed eliminarli.<\/p>\n\n\n\n<div id=\"for-windows-98-xp-and-7\" dir=\"LTR\">\n<div id=\"for-windows-8-and-8-1\" dir=\"LTR\">\n<figure><img wpfc-lazyload-disable=\"true\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6476 size-full\" title=\"Step3\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step3.png\" alt=\"Step3\" width=\"97\" height=\"24\" \/><\/figure>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">\u00a0<\/p>\n<p>Nel terzo passaggio, utilizzare Winkey + R per aprire la finestra di dialogo Esegui, quindi digitare il seguente comando e premere Invio:<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\"><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>notepad %windir%\/system32\/Drivers\/etc\/hosts<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">Si aprir\u00e0 un nuovo file. Se siete stati hackerati, in fondo ci sar\u00e0 un gruppo di altri IP collegati a voi. Guardate l&#8217;immagine qui sotto:<\/p>\n<figure><img wpfc-lazyload-disable=\"true\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3349 size-full\" title=\"Hosts file\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/07\/hosts_opt-1.png\" alt=\"hosts_opt (1)\" width=\"350\" height=\"185\" \/><\/figure>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">\u00a0<\/p>\n<p>In un secondo, apparir\u00e0 un documento con il nome Hosts. Cercate nel testo del documento la voce Localhost e cercate eventuali indirizzi IP strani. Non esitate a segnalarci eventuali indirizzi IP sospetti nei commenti qui sotto, in modo che possiamo darvi un&#8217;occhiata e darvi qualche indicazione.<\/p>\n<div id=\"for-windows-98-xp-and-7\" dir=\"LTR\">\n<div id=\"for-windows-8-and-8-1\" dir=\"LTR\">\n<p>Quindi, digitare &#8220;msconfig&#8221; nella barra di ricerca di Windows nel menu Start e premere Invio per avviare la finestra di configurazione del sistema. Fate clic sulla scheda Avvio ed esaminate gli elementi impostati per essere caricati all&#8217;avvio. Deselezionare la casella accanto alle voci di avvio che si sospetta possano essere associate al ransomware, quindi fare clic su &#8220;OK&#8221; per salvare le modifiche.<\/p>\n<figure><img wpfc-lazyload-disable=\"true\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3262 size-full\" title=\"System Configuration\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/07\/msconfig_opt.png\" alt=\"msconfig_opt\" width=\"350\" height=\"233\" \/><\/figure>\n<p>\u00a0<\/p>\n<\/div>\n<\/div>\n<figure><img wpfc-lazyload-disable=\"true\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6477 size-full\" title=\"Step4\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step4.png\" alt=\"Step4\" width=\"97\" height=\"24\" \/><\/figure>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">\u00a0<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\"><div class='code-block code-block-31' style='margin: 8px 0; clear: both;'>\n<div class=\"grey-bg\" id=\"secondguide_it\" style=\"background:#fcfcfc url(\/wp-content\/uploads\/2020\/01\/web-11.png) 25px 65px no-repeat; box-shadow:4px 10px 8px -6px rgba(239, 239, 239, 0.9); margin-bottom:25px; padding:20px 20px 20px 130px; position:relative; text-align:left\">\n<p style=\"font-size:16px; margin-bottom:30px; margin-top:0px\">Per rimuovere <strong>parasite<\/strong> da soli, potreste dover toccare I file del sistema e I registri. <span style=\"font-size:12.0pt\"><span style=\"line-height:107%\"><span> <\/span><\/span><\/span><span style=\"color:#2f5496\">Se doveste farlo, dovrete essere estremamente attenti perch&eacute; potreste danneggiare il vostro sistema.<\/span><\/p>\n<p style=\"font-size:16px; margin-bottom:30px; margin-top:0px\"><span style=\"color:#2f5496\">Se volete evitare il rischio, raccomandiamo di <a href=\"https:\/\/howtoremove.guide\/download-pc-spyhunter-it\/\">scaricare SpyHunter<\/a>, un tool professionale per la rimozione dei malware.<\/span><\/p>\n<p style=\"color:#9a9a9a; font-size:10px; text-align:center\">&nbsp;<\/p>\n<\/div><\/div>\n\n<p>Un software dannoso come Fate pu\u00f2 nascondere i suoi file in diverse posizioni del computer, compreso il registro di sistema. Per questo motivo, \u00e8 necessario trovare tutti i file correlati a Fate nell&#8217;Editor del Registro di sistema ed eliminarli. Digitare regedit nella barra di ricerca di Windows e premere Invio per aprire l&#8217;Editor del Registro di sistema.<\/p>\n<p>Premendo contemporaneamente i tasti Control e F si apre una finestra di ricerca in cui \u00e8 possibile cercare i file infetti. Per individuare un pericolo specifico, digitate il suo nome nella casella &#8220;Trova&#8221; e poi premete il pulsante &#8220;Trova successivo&#8221;.<\/p>\n<p>Attenzione! Per i non esperti pu\u00f2 essere difficile rimuovere le voci del registro di sistema relative al ransomware. L&#8217;eliminazione di una voce errata nel registro di sistema potrebbe causare gravi danni al sistema operativo, quindi va evitata a tutti i costi. Se si sospetta che il computer sia ancora infetto e che i file correlati a Fate siano nascosti in qualche posizione, \u00e8 necessario utilizzare il programma di rimozione malware professionale disponibile sul nostro sito web. Il programma \u00e8 utile non solo per rimuovere il malware presente, ma anche per proteggersi da future infezioni da malware e virus.<\/p>\n<p>Dovreste anche controllare le cinque posizioni qui sotto per verificare la presenza di eventuali altri file correlati al malware sul vostro computer. \u00c8 sufficiente digitare ciascuno dei seguenti elementi nella barra di ricerca di Windows e premere Invio per aprirli:<\/p>\n<ol>\n<li><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>%AppData%<\/strong><\/span><\/li>\n<li><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>%LocalAppData%<\/strong><\/span><\/li>\n<li><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>%ProgramData%<\/strong><\/span><\/li>\n<li><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>%WinDir%<\/strong><\/span><\/li>\n<li><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>%Temp%<\/strong><\/span><\/li>\n<\/ol>\n<p>Cercare in ogni cartella eventuali file dubbi aggiunti di recente, ma non eliminare nulla a meno che non si sia certi che faccia parte del problema. Selezionare i file nella cartella Temp, quindi premere il tasto Canc della tastiera per rimuovere tutti i file temporanei dal computer.<\/p>\n<figure><img wpfc-lazyload-disable=\"true\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6478 size-full\" title=\"Step 5\" src=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step5.png\" alt=\"Step5\" width=\"97\" height=\"24\" \/><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><strong><span style=\"font-size: 18pt;\">\u00a0<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 24px;\"><strong>Come decriptare i file Fate<\/strong><\/span><\/p>\n<p style=\"color: #252525;\">Le informazioni crittografate da un ransomware possono essere difficili da decifrare per chiunque non abbia esperienza tecnica. Questo perch\u00e9 ogni variante di ransomware ha i suoi metodi specifici di decriptazione che richiedono un approccio individuale. Per determinare quale metodo di decriptazione utilizzare, \u00e8 necessario innanzitutto capire quale variante di ransomware ha attaccato il computer. In genere \u00e8 possibile trovare questa informazione osservando le estensioni dei file aggiunti ai file crittografati.<\/p>\n<p style=\"color: #252525;\">Una scansione completa del sistema con uno strumento antivirus di alto livello \u00e8 un prerequisito per qualsiasi tentativo di recupero dei dati. Finch\u00e9 la scansione del malware non produce risultati di malware, non si dovrebbe nemmeno pensare di esplorare le soluzioni di recupero dei file.<\/p>\n<p style=\"color: #252525;\"><span style=\"font-size: 24px;\"><strong>Nuovo ransomware Djvu<\/strong><\/span><\/p>\n<p style=\"color: #252525;\">STOP Djvu \u00e8 una nuova variante di ransomware che ha causato un&#8217;interruzione diffusa crittografando i file e richiedendo il pagamento di un riscatto alle vittime. Le segnalazioni di attacchi da parte di questa minaccia sono state ricevute da tutto il mondo e ci\u00f2 per cui questo malware \u00e8 noto \u00e8 che tipicamente aggiunge l&#8217;estensione .Fate ai file crittografati. Se vi \u00e8 stato chiesto di pagare un riscatto, non dovreste farlo. I decrittatori, come quello che si trova al link sottostante, potrebbero aiutarvi a recuperare i vostri dati crittografati.<\/p>\n<p style=\"color: #252525;\"><strong>Decrittatore &#8211; <a href=\"https:\/\/www.emsisoft.com\/ransomware-decryption\/stop-djvu\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.emsisoft.com\/ransomware-decryption\/stop-djvu\/<\/a><\/strong><\/p>\n<p style=\"color: #252525;\">\u00c8 possibile scaricare il file eseguibile STOPDjvu dall&#8217;URL e salvarlo sul computer. Per sapere come funziona il software, assicuratevi di leggere il contratto di licenza e le istruzioni incluse prima di tentare di decifrare i file. \u00c8 fondamentale ricordare, tuttavia, che il software potrebbe non essere in grado di decodificare tutti i dati crittografati, soprattutto se i file sono stati crittografati utilizzando chiavi offline o tecniche di crittografia online sconosciute.<\/p>\n<p style=\"color: #252525;\">Se le soluzioni manuali qui fornite non sono sufficienti per affrontare Fate e il ransomware si rivela pi\u00f9 difficile del previsto, potreste voler utilizzare il software antivirus professionale consigliato nell&#8217;articolo per rimuovere rapidamente ed efficacemente il ransomware una volta per tutte. Se siete preoccupati per un file specifico, potete utilizzare il nostro <a href=\"https:\/\/howtoremove.guide\/online-virus-scanner\/\" target=\"_blank\" rel=\"noopener\">scanner antivirus online gratuito<\/a> per controllarlo manualmente.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fate Fate \u00e8 un rappresentante del gruppo di cryptovirus Ransomware che prende di mira diversi computer per criptare i file in essi memorizzati. I criminali informatici che si celano dietro Fate lo utilizzano per chiedere un riscatto alle loro vittime in cambio della fornitura di una chiave di decriptazione dei file. Il nostro team di [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[9597],"tags":[],"class_list":["post-189981","post","type-post","status-publish","format-standard","hentry","category-ransomware-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fate Virus Ransomware (.fate) Rimozione e Decrittografia dei file<\/title>\n<meta name=\"description\" content=\"Fate \u00e8 un rappresentante del gruppo di cryptovirus Ransomware che prende di mira diversi computer per criptare i file in essi memorizzati.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fate Virus Ransomware (.fate) Rimozione e Decrittografia dei file\" \/>\n<meta property=\"og:description\" content=\"Fate \u00e8 un rappresentante del gruppo di cryptovirus Ransomware che prende di mira diversi computer per criptare i file in essi memorizzati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/\" \/>\n<meta property=\"og:site_name\" content=\"HowToRemove.Guide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/howtoremove.guide\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-12T21:36:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-12T21:36:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png\" \/>\n<meta name=\"author\" content=\"George Slaine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GuideBasics\" \/>\n<meta name=\"twitter:site\" content=\"@GuideBasics\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Slaine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fate Virus Ransomware (.fate) Rimozione e Decrittografia dei file","description":"Fate \u00e8 un rappresentante del gruppo di cryptovirus Ransomware che prende di mira diversi computer per criptare i file in essi memorizzati.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/","og_locale":"it_IT","og_type":"article","og_title":"Fate Virus Ransomware (.fate) Rimozione e Decrittografia dei file","og_description":"Fate \u00e8 un rappresentante del gruppo di cryptovirus Ransomware che prende di mira diversi computer per criptare i file in essi memorizzati.","og_url":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/","og_site_name":"HowToRemove.Guide","article_publisher":"https:\/\/www.facebook.com\/howtoremove.guide","article_published_time":"2022-11-12T21:36:08+00:00","article_modified_time":"2022-11-12T21:36:13+00:00","og_image":[{"url":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","type":"","width":"","height":""}],"author":"George Slaine","twitter_card":"summary_large_image","twitter_creator":"@GuideBasics","twitter_site":"@GuideBasics","twitter_misc":{"Scritto da":"George Slaine","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/#article","isPartOf":{"@id":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/"},"author":{"name":"George Slaine","@id":"https:\/\/howtoremove.guide\/it\/#\/schema\/person\/21c82db8a1f4d7cf888c5c02c079d8d8"},"headline":"Fate Virus","datePublished":"2022-11-12T21:36:08+00:00","dateModified":"2022-11-12T21:36:13+00:00","mainEntityOfPage":{"@id":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/"},"wordCount":1719,"commentCount":0,"publisher":{"@id":"https:\/\/howtoremove.guide\/it\/#organization"},"image":{"@id":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/#primaryimage"},"thumbnailUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","articleSection":["Ransomware"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/","url":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/","name":"Fate Virus Ransomware (.fate) Rimozione e Decrittografia dei file","isPartOf":{"@id":"https:\/\/howtoremove.guide\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/#primaryimage"},"image":{"@id":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/#primaryimage"},"thumbnailUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","datePublished":"2022-11-12T21:36:08+00:00","dateModified":"2022-11-12T21:36:13+00:00","description":"Fate \u00e8 un rappresentante del gruppo di cryptovirus Ransomware che prende di mira diversi computer per criptare i file in essi memorizzati.","breadcrumb":{"@id":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/#primaryimage","url":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png","contentUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2015\/10\/Step1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/howtoremove.guide\/it\/rimuovere-fate-virus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/howtoremove.guide\/it\/"},{"@type":"ListItem","position":2,"name":"Ransomware","item":"https:\/\/howtoremove.guide\/it\/category\/ransomware-it\/"},{"@type":"ListItem","position":3,"name":"Fate Virus"}]},{"@type":"WebSite","@id":"https:\/\/howtoremove.guide\/it\/#website","url":"https:\/\/howtoremove.guide\/it\/","name":"HowToRemove.Guide","description":"Virus &amp; Malware Removal","publisher":{"@id":"https:\/\/howtoremove.guide\/it\/#organization"},"alternateName":"HowToRemove.guide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/howtoremove.guide\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/howtoremove.guide\/it\/#organization","name":"HowToRemove.Guide","url":"https:\/\/howtoremove.guide\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/howtoremove.guide\/it\/#\/schema\/logo\/image\/","url":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2018\/09\/howtoremove-logo-250-px.png","contentUrl":"https:\/\/howtoremove.guide\/wp-content\/uploads\/2018\/09\/howtoremove-logo-250-px.png","width":250,"height":42,"caption":"HowToRemove.Guide"},"image":{"@id":"https:\/\/howtoremove.guide\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/howtoremove.guide","https:\/\/x.com\/GuideBasics","https:\/\/www.youtube.com\/channel\/UCb61rHhYyMKutbMLc5r6w-w"]},{"@type":"Person","@id":"https:\/\/howtoremove.guide\/it\/#\/schema\/person\/21c82db8a1f4d7cf888c5c02c079d8d8","name":"George Slaine","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/howtoremove.guide\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/17047dcdf6307b0bc9558fc516840e6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17047dcdf6307b0bc9558fc516840e6c?s=96&d=mm&r=g","caption":"George Slaine"},"url":"https:\/\/howtoremove.guide\/it\/author\/georges\/"}]}},"spectra_custom_meta":{"_edit_lock":["1668288975:15"],"VirusName":["Fate"],"_edit_last":["15"],"_single_add_custom_css":[""],"_vce_meta":["a:4:{s:11:\"use_sidebar\";s:7:\"inherit\";s:7:\"sidebar\";s:7:\"inherit\";s:14:\"sticky_sidebar\";s:7:\"inherit\";s:6:\"layout\";s:7:\"inherit\";}"],"_yoast_wpseo_primary_category":["9597"],"_yoast_wpseo_title":["Fate Virus Ransomware (.fate) Rimozione e Decrittografia dei file %%page%%"],"_yoast_wpseo_metadesc":["Fate \u00e8 un rappresentante del gruppo di cryptovirus Ransomware che prende di mira diversi computer per criptare i file in essi memorizzati."],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":["10"],"_yoast_wpseo_wordproof_timestamp":[""],"_uag_page_assets":["a:9:{s:3:\"css\";s:4944:\".wp-block-uagb-separator{text-align:center;box-sizing:border-box;line-height:0}.wp-block-uagb-separator__inner{display:inline-block}.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner{display:flex;justify-content:center;align-items:center;margin:0 auto}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::before,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::after,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::after{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--icon .wp-block-uagb-separator-element svg{font-size:30px;color:#333;fill:#333;width:30px;height:30px;line-height:30px;max-width:none}.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{word-break:initial;margin:0}\n.uagb-block-9f7858eb.wp-block-uagb-separator{text-align: center;}.uagb-block-9f7858eb.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-9f7858eb.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 90%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}@media only screen and (max-width: 976px) {.uagb-block-9f7858eb.wp-block-uagb-separator{text-align: center;}.uagb-block-9f7858eb.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-9f7858eb.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}@media only screen and (max-width: 767px) {.uagb-block-9f7858eb.wp-block-uagb-separator{text-align: center;}.uagb-block-9f7858eb.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-9f7858eb.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}.uagb-block-f3a675c7.wp-block-uagb-separator{text-align: center;}.uagb-block-f3a675c7.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-f3a675c7.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 90%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}@media only screen and (max-width: 976px) {.uagb-block-f3a675c7.wp-block-uagb-separator{text-align: center;}.uagb-block-f3a675c7.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-f3a675c7.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}@media only screen and (max-width: 767px) {.uagb-block-f3a675c7.wp-block-uagb-separator{text-align: center;}.uagb-block-f3a675c7.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-f3a675c7.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: #e5e7eb;border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:34:{i:0;s:10:\"core\/group\";i:2;s:10:\"core\/image\";i:4;s:15:\"core\/navigation\";i:5;s:14:\"uagb\/separator\";i:7;s:15:\"core\/post-title\";i:9;s:16:\"core\/post-author\";i:10;s:14:\"core\/paragraph\";i:11;s:14:\"core\/post-date\";i:12;s:15:\"core\/post-terms\";i:15;s:24:\"core\/post-featured-image\";i:16;s:17:\"core\/post-content\";i:17;s:14:\"core\/separator\";i:19;s:13:\"core\/comments\";i:20;s:19:\"core\/comments-title\";i:21;s:21:\"core\/comment-template\";i:24;s:11:\"core\/avatar\";i:26;s:24:\"core\/comment-author-name\";i:28;s:17:\"core\/comment-date\";i:29;s:22:\"core\/comment-edit-link\";i:30;s:20:\"core\/comment-content\";i:31;s:23:\"core\/comment-reply-link\";i:32;s:24:\"core\/comments-pagination\";i:33;s:33:\"core\/comments-pagination-previous\";i:34;s:32:\"core\/comments-pagination-numbers\";i:35;s:29:\"core\/comments-pagination-next\";i:36;s:23:\"core\/post-comments-form\";i:38;s:12:\"core\/columns\";i:39;s:11:\"core\/column\";i:40;s:22:\"wpml\/language-switcher\";i:41;s:15:\"core\/site-title\";i:42;s:12:\"core\/heading\";i:43;s:10:\"core\/table\";i:44;s:9:\"core\/list\";i:45;s:22:\"tadv\/classic-paragraph\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1784059105;s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"rank_math_primary_category":["9597"],"rank_math_title":["Fate Virus Ransomware (.fate) Rimozione e Decrittografia dei file %page%"],"rank_math_description":["Fate \u00e8 un rappresentante del gruppo di cryptovirus Ransomware che prende di mira diversi computer per criptare i file in essi memorizzati."],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"_uag_css_file_name":["uag-css-189981.css"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"George Slaine","author_link":"https:\/\/howtoremove.guide\/it\/author\/georges\/"},"uagb_comment_info":0,"uagb_excerpt":"Fate Fate \u00e8 un rappresentante del gruppo di cryptovirus Ransomware che prende di mira diversi computer per criptare i file in essi memorizzati. I criminali informatici che si celano dietro Fate lo utilizzano per chiedere un riscatto alle loro vittime in cambio della fornitura di una chiave di decriptazione dei file. Il nostro team di&hellip;","_links":{"self":[{"href":"https:\/\/howtoremove.guide\/it\/wp-json\/wp\/v2\/posts\/189981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howtoremove.guide\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howtoremove.guide\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howtoremove.guide\/it\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/howtoremove.guide\/it\/wp-json\/wp\/v2\/comments?post=189981"}],"version-history":[{"count":0,"href":"https:\/\/howtoremove.guide\/it\/wp-json\/wp\/v2\/posts\/189981\/revisions"}],"wp:attachment":[{"href":"https:\/\/howtoremove.guide\/it\/wp-json\/wp\/v2\/media?parent=189981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howtoremove.guide\/it\/wp-json\/wp\/v2\/categories?post=189981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howtoremove.guide\/it\/wp-json\/wp\/v2\/tags?post=189981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}